{"id":7911,"date":"2015-12-08T09:46:44","date_gmt":"2015-12-08T08:46:44","guid":{"rendered":"http:\/\/www.jazzzeitung.de\/cms\/?p=7911"},"modified":"2015-12-08T09:46:44","modified_gmt":"2015-12-08T08:46:44","slug":"news-veranstaltungstipps-ticker-burghauser-nachwuchs-jazzpreis-early-bird-tickets-moers","status":"publish","type":"post","link":"https:\/\/www.jazzzeitung.de\/cms\/2015\/12\/news-veranstaltungstipps-ticker-burghauser-nachwuchs-jazzpreis-early-bird-tickets-moers\/","title":{"rendered":"+++ News +++ Veranstaltungstipps-Ticker +++ Burghauser Nachwuchs-Jazzpreis +++ Early Bird Tickets Moers +++"},"content":{"rendered":"<p>+++ Jazzclub Regensburg mit Lorenz Kellhuber und Lisa Bassenge +++<\/p>\n<p><a href=\"https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2015\/12\/jc-20151213-Jazz%C2%B4n-Soul-Weihnachtsparty.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"7912\" data-permalink=\"https:\/\/www.jazzzeitung.de\/cms\/2015\/12\/news-veranstaltungstipps-ticker-burghauser-nachwuchs-jazzpreis-early-bird-tickets-moers\/jc-20151213-jazzn-soul-weihnachtsparty\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2015\/12\/jc-20151213-Jazz%C2%B4n-Soul-Weihnachtsparty.jpg?fit=3000%2C3150&amp;ssl=1\" data-orig-size=\"3000,3150\" data-comments-opened=\"1\" data-image-title=\"jc 20151213 Jazz\u00b4n Soul Weihnachtsparty\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2015\/12\/jc-20151213-Jazz%C2%B4n-Soul-Weihnachtsparty.jpg?fit=571%2C600&amp;ssl=1\" class=\"alignright size-thumbnail wp-image-7912\" src=\"https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2015\/12\/jc-20151213-Jazz%C2%B4n-Soul-Weihnachtsparty-150x150.jpg?resize=150%2C150\" alt=\"jc 20151213 Jazz\u00b4n Soul Weihnachtsparty\" width=\"150\" height=\"150\" srcset=\"https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2015\/12\/jc-20151213-Jazz%C2%B4n-Soul-Weihnachtsparty.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2015\/12\/jc-20151213-Jazz%C2%B4n-Soul-Weihnachtsparty.jpg?resize=144%2C144&amp;ssl=1 144w, https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2015\/12\/jc-20151213-Jazz%C2%B4n-Soul-Weihnachtsparty.jpg?resize=96%2C96&amp;ssl=1 96w, https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2015\/12\/jc-20151213-Jazz%C2%B4n-Soul-Weihnachtsparty.jpg?resize=24%2C24&amp;ssl=1 24w, https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2015\/12\/jc-20151213-Jazz%C2%B4n-Soul-Weihnachtsparty.jpg?resize=36%2C36&amp;ssl=1 36w, https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2015\/12\/jc-20151213-Jazz%C2%B4n-Soul-Weihnachtsparty.jpg?resize=48%2C48&amp;ssl=1 48w, https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2015\/12\/jc-20151213-Jazz%C2%B4n-Soul-Weihnachtsparty.jpg?resize=64%2C64&amp;ssl=1 64w, https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2015\/12\/jc-20151213-Jazz%C2%B4n-Soul-Weihnachtsparty.jpg?resize=32%2C32&amp;ssl=1 32w, https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2015\/12\/jc-20151213-Jazz%C2%B4n-Soul-Weihnachtsparty.jpg?resize=128%2C128&amp;ssl=1 128w, https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2015\/12\/jc-20151213-Jazz%C2%B4n-Soul-Weihnachtsparty.jpg?zoom=2&amp;resize=150%2C150&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2015\/12\/jc-20151213-Jazz%C2%B4n-Soul-Weihnachtsparty.jpg?zoom=3&amp;resize=150%2C150&amp;ssl=1 450w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>Der <strong>Jazzclub Regensburg<\/strong> pr\u00e4sentiert am Donnerstag, den 10.12.2015, 20:00 Uhr, das Pianotrio von Lorenz Kellhuber bei Jazz in der Galerie;\u00a0 <strong>Besetzung:<\/strong> Lorenz Kellhuber \u2013 p | Orlando le Fleming \u2013 b | Obed Calvaire \u2013 dr &#8211; Sp\u00e4testens seit seinem zweiten, hoch gelobten Album COSMOS gilt der 25-j\u00e4hrige Pianist und Komponist LORENZ KELLHUBER als au\u00dfergew\u00f6hnliches Talent in der Jazzszene. Zu diesem Konzert kommt er mit seinem New Yorker Trio, f\u00fcr das er zwei der gefragtesten Musiker der dortigen Jazzszene gewinnen konnte: Mit ORLANDO LE FLEMING am Bass und OBED CALVAIRE am Schlagzeug interpretiert er dabei St\u00fccke aus dem Great American Songbook.<\/p>\n<p>Am Sonntag, den 13. Dezember wird es weihnachtlich mit R\u00fcdiger Eisenhauers Sleigh Ride Orchestra feat. Lisa Bassenge; <strong>Besetzung:<\/strong> S(w)inging Angels: Martin Strasser \u2013 voc | Klaudia Salkovic \u2013 voc; Sleigh Ride Orchestra: Dirk Rumig \u2013 sax | R\u00fcdiger Eisenhauer \u2013 g | Matthias Bublath \u2013 org | Felix Wiegand \u2013 b | Guido May \u2013 dr<\/p>\n<p>Special Guest: Lisa Bassenge \u2013 voc &#8211; Tiki, Rockabilly und Swing Extravaganza is in the House. Das Sleigh Ride Orchestra l\u00e4sst bereits zum vierten Mal den Weihnachtsschlitten \u00fcber dem Kamin im Leeren Beutel anhalten und feiert mit musikalischen Leckerbissen. Die bekannten Christmas Crooner MARTIN STRASSER und KLAUDIA SALKOVIC und special guest LISA BASSENGE shaken, mixen und servieren unter Mastermind R\u00dcDIGER EISENHAUER einen hei\u00dfen Christmas Cocktail mit der extra Kirsche drin. Groovin\u00b4 and Rockin\u00b4 around the Christmas Tree! Shake your booty, do your hair, dress in style and let Christmas shine! w<a href=\"http:\/\/ww.jazzclub-regensburg.de\">ww.jazzclub-regensburg.de<\/a><\/p>\n<p>+++<\/p>\n<p>Das Programm des <strong>8. JazzFr\u00fchlings Kassel vom 05.-20.03.2016<\/strong> pr\u00e4sentiert \u00fcber zwei Wochen die schillernden Facetten des Jazz. Schon das Auftaktkonzert am 05. M\u00e4rz mit <strong>Sebastian Studnitzky<\/strong> und seinem Programm Momento gibt eindrucksvoll Einblicke in die Vielseitigkeit des Jazz. Ein wahres Feuerwerk der Emotionen erweckt Studnitzky, wenn er zusammen mit seinem Kammerorchester geschmackvoll die Grenzen der musikalischen Genre zwischen Jazz, Klassik und Pop auslotet. Und auch einen <strong>Michael Wollny<\/strong> liebt das Publikum f\u00fcr seine expressive Experimentierfreude. \u00dcberhaupt werden Emotionen in den \u00fcber zwei Wochen des 08. JazzFr\u00fchlings gro\u00df geschrieben \u2013 daf\u00fcr stehen Namen wie <strong>China Moses, Till Br\u00f6nner, Chico Freemann, The Cookers, Ed Motta<\/strong> und viele mehr.<br \/>\nOb im intimen Theaterst\u00fcbchen selbst mit seinen 180 Sitzen oder unter dem Motto \u201eTheaterst\u00fcbchen geht fremd\u201c im Theater der Kassler Staatsoper, im Ballsaal des Hotel Reiss\u2018 oder im Foyer der Kasseler Bank, eins ist gewiss: Das Programm wimmelt von internationalen Garanten des musikalischen K\u00f6nnens, des Entertainments und des guten Tons.<br \/>\nMit ein bisschen Stolz sagt Macher Markus Knierim: \u201eDass selbst ein Jan Gabarek den JazzFr\u00fchling dazu ausgesucht hat, sein neues Programm zusammen mit Trilok Gurtu zum ersten Mal der \u00d6ffentlichkeit zu pr\u00e4sentieren, ist ein Ritterschlag!\u201c &#8211; <strong>Vorverkaufs-Start f\u00fcr alle Konzerte: 7. Dezember 2015!<\/strong>\u00a0<a href=\"http:\/\/www.theaterstuebchen.de\">www.theaterstuebchen.de<\/a><\/p>\n<p>&nbsp;<\/p>\n<p><strong>+++ Burghauser Jazz-Nachwuchspreis +++<\/strong><\/p>\n<p>Ein Erfolgsmodell geht in die n\u00e4chste Runde. Zum 8. Mal werden im M\u00e4rz 2016 junge Bands im Stadtsaal von Burghausen antreten, um als Sieger den begehrten <strong>Europ\u00e4ischen Burghauser Nachwuchs-Jazzpreis <\/strong>zu ergattern. Insgesamt haben sich 62 Gruppen aus ganz Europa beworben, f\u00fcnf davon werden im Anschluss an das Bewertungsverfahren der vierk\u00f6pfigen Fachjury zum Finale eingeladen. Und da das spieltechnische Niveau der jungen Musiker stetig steigt, wird es auch diesmal ein Kopf-an-Kopf-Rennen der Nachwuchskoryph\u00e4en geben. Die Finalisten werden Mitte Dezember bekannt gegeben, das <strong>Wettbewerbskonzert findet am 8. M\u00e4rz 2016<\/strong> statt.<\/p>\n<p><em>\u201eViele der Bands und Solisten wie etwa der Gitarrist Marius Peters, der Saxofonist Malte Schiller oder der Pianist Elliot Galvin, die w\u00e4hrend der vergangenen Jahre den Wettbewerb gewonnen habe, geh\u00f6ren bereits zu den wichtigen neuen Kr\u00e4ften des Jazz in Europa. Und ich bin mir sicher, dass auch im kommenden Jahr wieder grandiose Talente in Burghausen zu h\u00f6ren sein werden.\u201c (<\/em>Ralf Dombrowski f\u00fcr die Jury)<\/p>\n<p>&nbsp;<\/p>\n<p><strong>+++ Verkaufstart Early-Bird-Tickets Moers +++<\/strong><\/p>\n<p>Der Verkauf der <a href=\"http:\/\/moers-festival.us10.list-manage2.com\/track\/click?u=81c03e6d862676984262841b9&amp;id=29008472b6&amp;e=32b6a1150e\"><strong>Early-Bird-Tickets<\/strong><\/a> f\u00fcr das moers festival hat begonnen: Passend zur Adventszeit wird traditionell das Festivalticket f\u00fcr die kompletten vier Festivaltage (13.-16. Mai 2016) zum besonders g\u00fcnstigen Preis angeboten. Ein beliebtes Geschenk f\u00fcr musikaffine Freunde und Familie oder einfach euer Geschenk an euch selbst. Wie bereits Anfang November berichtetet, mussten die Ticketpreise f\u00fcr das kommende moers festival leider insgesamt erh\u00f6ht werden. Nichtsdestotrotz zahlt ihr f\u00fcr das Early-Bird-Ticket nur 108 Euro anstatt der 140 Euro an der Abendkasse. Die erm\u00e4\u00dfigte Version wurde nicht erh\u00f6ht, sie kostet weiterhin nur 50 Euro. Also ab zum <a href=\"http:\/\/moers-festival.us10.list-manage1.com\/track\/click?u=81c03e6d862676984262841b9&amp;id=4128667f68&amp;e=32b6a1150e\"><strong>Ticketshop<\/strong><\/a>, denn wie immer gibt es das Early-Bird-Ticket nur solange der Vorrat reicht.<\/p>\n<p>Improviser in Residence<\/p>\n<p>Noch bis Ende des Jahres wird der <strong>Improviser in Residence Hayden Chisholm<\/strong>\u00a0den Festivalgeist in Moers mit unterschiedlichsten Aktionen und Projekten am Leben erhalten. Danach ist es Zeit, eine(n) neuen Improviser in Residence zu begr\u00fc\u00dfen. Wer das ist, wird noch nicht verraten. Den Termin des \u00dcbergabekonzerts geben wir aber jetzt schon bekannt: <strong>21. Januar 2016<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<table style=\"height: 82px;\" width=\"591\">\n<tbody>\n<tr>\n<td><\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p>+++ Jazzclub Regensburg mit Lorenz Kellhuber und Lisa Bassenge +++ Der Jazzclub Regensburg pr\u00e4sentiert am Donnerstag, den 10.12.2015, 20:00 Uhr, das Pianotrio von Lorenz Kellhuber bei Jazz in der Galerie;\u00a0 Besetzung: Lorenz Kellhuber \u2013 p | Orlando le Fleming \u2013 b | Obed Calvaire \u2013 dr &#8211; Sp\u00e4testens seit seinem zweiten, hoch gelobten Album COSMOS gilt der 25-j\u00e4hrige Pianist und Komponist LORENZ KELLHUBER als au\u00dfergew\u00f6hnliches Talent in der Jazzszene. Zu diesem Konzert kommt er mit seinem New Yorker Trio, f\u00fcr das er zwei der gefragtesten Musiker der dortigen Jazzszene gewinnen konnte: Mit ORLANDO LE FLEMING am Bass und OBED CALVAIRE am Schlagzeug interpretiert er dabei St\u00fccke aus dem Great American Songbook. Am Sonntag, den 13. Dezember wird es weihnachtlich mit R\u00fcdiger Eisenhauers Sleigh Ride Orchestra feat. Lisa Bassenge; Besetzung: S(w)inging Angels: Martin Strasser \u2013 voc | Klaudia Salkovic \u2013 voc; Sleigh Ride Orchestra: Dirk Rumig \u2013 sax | R\u00fcdiger Eisenhauer \u2013 g | Matthias Bublath \u2013 org | Felix Wiegand \u2013 b | Guido May \u2013 dr Special Guest: Lisa Bassenge \u2013 voc &#8211; Tiki, Rockabilly und Swing Extravaganza is in the House. Das Sleigh &hellip;<\/p>\n","protected":false},"author":18,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[634],"tags":[34,722,945,1237,750,3,271,737,1239,316,322,323,1238,1036,380,388,396,397,870,447,146,1797,527,535,548,549,684,19],"coauthors":[695],"class_list":["post-7911","post","type-post","status-publish","format-standard","hentry","category-redaktion","tag-album","tag-burghausen","tag-burghauser-nachwuchs-jazzpreis","tag-early-bird-tickets-moers","tag-early-bird-ticket","tag-festival","tag-jazzclub","tag-jazzclub-regensburg","tag-jazzfruehling-kassel-europaeischer-jazznachwuchs-preis-burghausen","tag-klassik","tag-konzert-2","tag-konzerte","tag-lisa-bassenge","tag-lorenz-kellhuber","tag-matthias-bublath","tag-michael-wollny","tag-moers","tag-moers-festival","tag-nachwuchspreis","tag-pop","tag-dombrowski","tag-regensburg","tag-studnitzky","tag-swing","tag-tickets","tag-till-broenner","tag-trilok-gurtu","tag-wettbewerb"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>+++ News +++ Veranstaltungstipps-Ticker +++ Burghauser Nachwuchs-Jazzpreis +++ Early Bird Tickets Moers +++ - JazzZeitung<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.jazzzeitung.de\/cms\/2015\/12\/news-veranstaltungstipps-ticker-burghauser-nachwuchs-jazzpreis-early-bird-tickets-moers\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"+++ News +++ Veranstaltungstipps-Ticker +++ Burghauser Nachwuchs-Jazzpreis +++ Early Bird Tickets Moers +++ - JazzZeitung\" \/>\n<meta property=\"og:description\" content=\"+++ Jazzclub Regensburg mit Lorenz Kellhuber und Lisa Bassenge +++ Der Jazzclub Regensburg pr\u00e4sentiert am Donnerstag, den 10.12.2015, 20:00 Uhr, das Pianotrio von Lorenz Kellhuber bei Jazz in der Galerie;\u00a0 Besetzung: Lorenz Kellhuber \u2013 p | Orlando le Fleming \u2013 b | Obed Calvaire \u2013 dr &#8211; Sp\u00e4testens seit seinem zweiten, hoch gelobten Album COSMOS gilt der 25-j\u00e4hrige Pianist und Komponist LORENZ KELLHUBER als au\u00dfergew\u00f6hnliches Talent in der Jazzszene. Zu diesem Konzert kommt er mit seinem New Yorker Trio, f\u00fcr das er zwei der gefragtesten Musiker der dortigen Jazzszene gewinnen konnte: Mit ORLANDO LE FLEMING am Bass und OBED CALVAIRE am Schlagzeug interpretiert er dabei St\u00fccke aus dem Great American Songbook. Am Sonntag, den 13. Dezember wird es weihnachtlich mit R\u00fcdiger Eisenhauers Sleigh Ride Orchestra feat. Lisa Bassenge; Besetzung: S(w)inging Angels: Martin Strasser \u2013 voc | Klaudia Salkovic \u2013 voc; Sleigh Ride Orchestra: Dirk Rumig \u2013 sax | R\u00fcdiger Eisenhauer \u2013 g | Matthias Bublath \u2013 org | Felix Wiegand \u2013 b | Guido May \u2013 dr Special Guest: Lisa Bassenge \u2013 voc &#8211; Tiki, Rockabilly und Swing Extravaganza is in the House. Das Sleigh &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.jazzzeitung.de\/cms\/2015\/12\/news-veranstaltungstipps-ticker-burghauser-nachwuchs-jazzpreis-early-bird-tickets-moers\/\" \/>\n<meta property=\"og:site_name\" content=\"JazzZeitung\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/JazzZeitung\/\" \/>\n<meta property=\"article:published_time\" content=\"2015-12-08T08:46:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2012\/01\/ipad-logo-200.png?fit=200%2C200&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"200\" \/>\n\t<meta property=\"og:image:height\" content=\"200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Redaktion JazzZeitung\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.jazzzeitung.de\\\/cms\\\/2015\\\/12\\\/news-veranstaltungstipps-ticker-burghauser-nachwuchs-jazzpreis-early-bird-tickets-moers\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jazzzeitung.de\\\/cms\\\/2015\\\/12\\\/news-veranstaltungstipps-ticker-burghauser-nachwuchs-jazzpreis-early-bird-tickets-moers\\\/\"},\"author\":{\"name\":\"Redaktion JazzZeitung\",\"@id\":\"https:\\\/\\\/www.jazzzeitung.de\\\/cms\\\/#\\\/schema\\\/person\\\/2245b36b9cd1d24cea10f01c031fb92b\"},\"headline\":\"+++ News +++ Veranstaltungstipps-Ticker +++ Burghauser Nachwuchs-Jazzpreis +++ Early Bird Tickets Moers +++\",\"datePublished\":\"2015-12-08T08:46:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.jazzzeitung.de\\\/cms\\\/2015\\\/12\\\/news-veranstaltungstipps-ticker-burghauser-nachwuchs-jazzpreis-early-bird-tickets-moers\\\/\"},\"wordCount\":805,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.jazzzeitung.de\\\/cms\\\/#organization\"},\"keywords\":[\"Album\",\"Burghausen\",\"Burghauser Nachwuchs-Jazzpreis\",\"Early Bird Tickets Moers\",\"Early-bird-Ticket\",\"Festival\",\"Jazzclub\",\"Jazzclub Regensburg\",\"Jazzfr\u00fchling Kassel. Europ\u00e4ischer Jazznachwuchs-Preis Burghausen\",\"Klassik\",\"Konzert\",\"Konzerte\",\"Lisa Bassenge\",\"Lorenz Kellhuber\",\"Matthias Bublath\",\"Michael Wollny\",\"Moers\",\"Moers Festival\",\"Nachwuchspreis\",\"Pop\",\"Ralf Dombrowski\",\"Regensburg\",\"Studnitzky\",\"Swing\",\"Tickets\",\"Till Br\u00f6nner\",\"Trilok Gurtu\",\"Wettbewerb\"],\"articleSection\":[\"Redaktionelle Nachrichten\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.jazzzeitung.de\\\/cms\\\/2015\\\/12\\\/news-veranstaltungstipps-ticker-burghauser-nachwuchs-jazzpreis-early-bird-tickets-moers\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.jazzzeitung.de\\\/cms\\\/2015\\\/12\\\/news-veranstaltungstipps-ticker-burghauser-nachwuchs-jazzpreis-early-bird-tickets-moers\\\/\",\"url\":\"https:\\\/\\\/www.jazzzeitung.de\\\/cms\\\/2015\\\/12\\\/news-veranstaltungstipps-ticker-burghauser-nachwuchs-jazzpreis-early-bird-tickets-moers\\\/\",\"name\":\"+++ News +++ Veranstaltungstipps-Ticker +++ Burghauser Nachwuchs-Jazzpreis +++ Early Bird Tickets Moers +++ - JazzZeitung\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jazzzeitung.de\\\/cms\\\/#website\"},\"datePublished\":\"2015-12-08T08:46:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.jazzzeitung.de\\\/cms\\\/2015\\\/12\\\/news-veranstaltungstipps-ticker-burghauser-nachwuchs-jazzpreis-early-bird-tickets-moers\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.jazzzeitung.de\\\/cms\\\/2015\\\/12\\\/news-veranstaltungstipps-ticker-burghauser-nachwuchs-jazzpreis-early-bird-tickets-moers\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.jazzzeitung.de\\\/cms\\\/2015\\\/12\\\/news-veranstaltungstipps-ticker-burghauser-nachwuchs-jazzpreis-early-bird-tickets-moers\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.jazzzeitung.de\\\/cms\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"+++ News +++ Veranstaltungstipps-Ticker +++ Burghauser Nachwuchs-Jazzpreis +++ Early Bird Tickets Moers +++\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.jazzzeitung.de\\\/cms\\\/#website\",\"url\":\"https:\\\/\\\/www.jazzzeitung.de\\\/cms\\\/\",\"name\":\"JazzZeitung\",\"description\":\"Jazz-News und Jazz-Kontroverses\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.jazzzeitung.de\\\/cms\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.jazzzeitung.de\\\/cms\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.jazzzeitung.de\\\/cms\\\/#organization\",\"name\":\"JazzZeitung online\",\"url\":\"https:\\\/\\\/www.jazzzeitung.de\\\/cms\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.jazzzeitung.de\\\/cms\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.jazzzeitung.de\\\/cms\\\/wp-content\\\/uploads\\\/2015\\\/08\\\/JAZZZEITUNGDE_Logo_Neu.png?fit=499%2C200&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.jazzzeitung.de\\\/cms\\\/wp-content\\\/uploads\\\/2015\\\/08\\\/JAZZZEITUNGDE_Logo_Neu.png?fit=499%2C200&ssl=1\",\"width\":499,\"height\":200,\"caption\":\"JazzZeitung online\"},\"image\":{\"@id\":\"https:\\\/\\\/www.jazzzeitung.de\\\/cms\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/JazzZeitung\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.jazzzeitung.de\\\/cms\\\/#\\\/schema\\\/person\\\/2245b36b9cd1d24cea10f01c031fb92b\",\"name\":\"Redaktion JazzZeitung\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/i0.wp.com\\\/www.jazzzeitung.de\\\/cms\\\/wp-content\\\/uploads\\\/2015\\\/08\\\/JAZZZEITUNGDE_Logo_Neu.png?resize=96%2C96&ssl=159975dcacb611b5700bd619b5daf0a7a\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.jazzzeitung.de\\\/cms\\\/wp-content\\\/uploads\\\/2015\\\/08\\\/JAZZZEITUNGDE_Logo_Neu.png?resize=96%2C96&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.jazzzeitung.de\\\/cms\\\/wp-content\\\/uploads\\\/2015\\\/08\\\/JAZZZEITUNGDE_Logo_Neu.png?resize=96%2C96&ssl=1\",\"caption\":\"Redaktion JazzZeitung\"},\"description\":\"Artikel der Redaktion der JazzZeitung.\",\"sameAs\":[\"http:\\\/\\\/www.jazzzeitung.de\\\/cms\\\/\"],\"url\":\"https:\\\/\\\/www.jazzzeitung.de\\\/cms\\\/author\\\/redaktion\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"+++ News +++ Veranstaltungstipps-Ticker +++ Burghauser Nachwuchs-Jazzpreis +++ Early Bird Tickets Moers +++ - JazzZeitung","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.jazzzeitung.de\/cms\/2015\/12\/news-veranstaltungstipps-ticker-burghauser-nachwuchs-jazzpreis-early-bird-tickets-moers\/","og_locale":"de_DE","og_type":"article","og_title":"+++ News +++ Veranstaltungstipps-Ticker +++ Burghauser Nachwuchs-Jazzpreis +++ Early Bird Tickets Moers +++ - JazzZeitung","og_description":"+++ Jazzclub Regensburg mit Lorenz Kellhuber und Lisa Bassenge +++ Der Jazzclub Regensburg pr\u00e4sentiert am Donnerstag, den 10.12.2015, 20:00 Uhr, das Pianotrio von Lorenz Kellhuber bei Jazz in der Galerie;\u00a0 Besetzung: Lorenz Kellhuber \u2013 p | Orlando le Fleming \u2013 b | Obed Calvaire \u2013 dr &#8211; Sp\u00e4testens seit seinem zweiten, hoch gelobten Album COSMOS gilt der 25-j\u00e4hrige Pianist und Komponist LORENZ KELLHUBER als au\u00dfergew\u00f6hnliches Talent in der Jazzszene. Zu diesem Konzert kommt er mit seinem New Yorker Trio, f\u00fcr das er zwei der gefragtesten Musiker der dortigen Jazzszene gewinnen konnte: Mit ORLANDO LE FLEMING am Bass und OBED CALVAIRE am Schlagzeug interpretiert er dabei St\u00fccke aus dem Great American Songbook. Am Sonntag, den 13. Dezember wird es weihnachtlich mit R\u00fcdiger Eisenhauers Sleigh Ride Orchestra feat. Lisa Bassenge; Besetzung: S(w)inging Angels: Martin Strasser \u2013 voc | Klaudia Salkovic \u2013 voc; Sleigh Ride Orchestra: Dirk Rumig \u2013 sax | R\u00fcdiger Eisenhauer \u2013 g | Matthias Bublath \u2013 org | Felix Wiegand \u2013 b | Guido May \u2013 dr Special Guest: Lisa Bassenge \u2013 voc &#8211; Tiki, Rockabilly und Swing Extravaganza is in the House. Das Sleigh &hellip;","og_url":"https:\/\/www.jazzzeitung.de\/cms\/2015\/12\/news-veranstaltungstipps-ticker-burghauser-nachwuchs-jazzpreis-early-bird-tickets-moers\/","og_site_name":"JazzZeitung","article_publisher":"https:\/\/www.facebook.com\/JazzZeitung\/","article_published_time":"2015-12-08T08:46:44+00:00","og_image":[{"width":200,"height":200,"url":"https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2012\/01\/ipad-logo-200.png?fit=200%2C200&ssl=1","type":"image\/png"}],"author":"Redaktion JazzZeitung","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.jazzzeitung.de\/cms\/2015\/12\/news-veranstaltungstipps-ticker-burghauser-nachwuchs-jazzpreis-early-bird-tickets-moers\/#article","isPartOf":{"@id":"https:\/\/www.jazzzeitung.de\/cms\/2015\/12\/news-veranstaltungstipps-ticker-burghauser-nachwuchs-jazzpreis-early-bird-tickets-moers\/"},"author":{"name":"Redaktion JazzZeitung","@id":"https:\/\/www.jazzzeitung.de\/cms\/#\/schema\/person\/2245b36b9cd1d24cea10f01c031fb92b"},"headline":"+++ News +++ Veranstaltungstipps-Ticker +++ Burghauser Nachwuchs-Jazzpreis +++ Early Bird Tickets Moers +++","datePublished":"2015-12-08T08:46:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.jazzzeitung.de\/cms\/2015\/12\/news-veranstaltungstipps-ticker-burghauser-nachwuchs-jazzpreis-early-bird-tickets-moers\/"},"wordCount":805,"commentCount":0,"publisher":{"@id":"https:\/\/www.jazzzeitung.de\/cms\/#organization"},"keywords":["Album","Burghausen","Burghauser Nachwuchs-Jazzpreis","Early Bird Tickets Moers","Early-bird-Ticket","Festival","Jazzclub","Jazzclub Regensburg","Jazzfr\u00fchling Kassel. Europ\u00e4ischer Jazznachwuchs-Preis Burghausen","Klassik","Konzert","Konzerte","Lisa Bassenge","Lorenz Kellhuber","Matthias Bublath","Michael Wollny","Moers","Moers Festival","Nachwuchspreis","Pop","Ralf Dombrowski","Regensburg","Studnitzky","Swing","Tickets","Till Br\u00f6nner","Trilok Gurtu","Wettbewerb"],"articleSection":["Redaktionelle Nachrichten"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.jazzzeitung.de\/cms\/2015\/12\/news-veranstaltungstipps-ticker-burghauser-nachwuchs-jazzpreis-early-bird-tickets-moers\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.jazzzeitung.de\/cms\/2015\/12\/news-veranstaltungstipps-ticker-burghauser-nachwuchs-jazzpreis-early-bird-tickets-moers\/","url":"https:\/\/www.jazzzeitung.de\/cms\/2015\/12\/news-veranstaltungstipps-ticker-burghauser-nachwuchs-jazzpreis-early-bird-tickets-moers\/","name":"+++ News +++ Veranstaltungstipps-Ticker +++ Burghauser Nachwuchs-Jazzpreis +++ Early Bird Tickets Moers +++ - JazzZeitung","isPartOf":{"@id":"https:\/\/www.jazzzeitung.de\/cms\/#website"},"datePublished":"2015-12-08T08:46:44+00:00","breadcrumb":{"@id":"https:\/\/www.jazzzeitung.de\/cms\/2015\/12\/news-veranstaltungstipps-ticker-burghauser-nachwuchs-jazzpreis-early-bird-tickets-moers\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.jazzzeitung.de\/cms\/2015\/12\/news-veranstaltungstipps-ticker-burghauser-nachwuchs-jazzpreis-early-bird-tickets-moers\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.jazzzeitung.de\/cms\/2015\/12\/news-veranstaltungstipps-ticker-burghauser-nachwuchs-jazzpreis-early-bird-tickets-moers\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.jazzzeitung.de\/cms\/"},{"@type":"ListItem","position":2,"name":"+++ News +++ Veranstaltungstipps-Ticker +++ Burghauser Nachwuchs-Jazzpreis +++ Early Bird Tickets Moers +++"}]},{"@type":"WebSite","@id":"https:\/\/www.jazzzeitung.de\/cms\/#website","url":"https:\/\/www.jazzzeitung.de\/cms\/","name":"JazzZeitung","description":"Jazz-News und Jazz-Kontroverses","publisher":{"@id":"https:\/\/www.jazzzeitung.de\/cms\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.jazzzeitung.de\/cms\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.jazzzeitung.de\/cms\/#organization","name":"JazzZeitung online","url":"https:\/\/www.jazzzeitung.de\/cms\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.jazzzeitung.de\/cms\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2015\/08\/JAZZZEITUNGDE_Logo_Neu.png?fit=499%2C200&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2015\/08\/JAZZZEITUNGDE_Logo_Neu.png?fit=499%2C200&ssl=1","width":499,"height":200,"caption":"JazzZeitung online"},"image":{"@id":"https:\/\/www.jazzzeitung.de\/cms\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/JazzZeitung\/"]},{"@type":"Person","@id":"https:\/\/www.jazzzeitung.de\/cms\/#\/schema\/person\/2245b36b9cd1d24cea10f01c031fb92b","name":"Redaktion JazzZeitung","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2015\/08\/JAZZZEITUNGDE_Logo_Neu.png?resize=96%2C96&ssl=159975dcacb611b5700bd619b5daf0a7a","url":"https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2015\/08\/JAZZZEITUNGDE_Logo_Neu.png?resize=96%2C96&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2015\/08\/JAZZZEITUNGDE_Logo_Neu.png?resize=96%2C96&ssl=1","caption":"Redaktion JazzZeitung"},"description":"Artikel der Redaktion der JazzZeitung.","sameAs":["http:\/\/www.jazzzeitung.de\/cms\/"],"url":"https:\/\/www.jazzzeitung.de\/cms\/author\/redaktion\/"}]}},"wp-worthy-pixel":{"ignored":false,"public":null,"server":null,"url":null},"wp-worthy-type":"normal","jetpack_publicize_connections":[],"cc_featured_image_caption":{"caption_text":false,"source_text":false,"source_url":false},"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p3KEcT-23B","jetpack-related-posts":[{"id":8167,"url":"https:\/\/www.jazzzeitung.de\/cms\/2016\/01\/lorenz-kellhuber-live-hfkm-regensburg-erstmalneues7\/","url_meta":{"origin":7911,"position":0},"title":"Lorenz Kellhuber Live @ HfKM Regensburg  \/\/ erstmalneues7","author":"Thomas J. Krebs","date":"21. Januar 2016","format":false,"excerpt":"Der in M\u00fcnchen geborene und mittlerweile Wahl-Berliner Pianist Lorenz Kellhuber ist ein wirklich au\u00dfergew\u00f6hnliches Talent und musikalisch immens umtriebig. Im Dezember war der Pianist gerade mit seinem Standards Trio (gemeinsam mit Orlando le Fleming am Bass und dem Schlagzeuger Obed Calvaire) im Jazzclub Regensburg und stellte sein aktuelles Standards Album\u2026","rel":"","context":"In &quot;Redaktionelle Nachrichten&quot;","block_context":{"text":"Redaktionelle Nachrichten","link":"https:\/\/www.jazzzeitung.de\/cms\/thema\/redaktion\/"},"img":{"alt_text":"Kellhuber - Foto TJ Krebs","src":"https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2016\/01\/P1410349_Kellhuber-Foto-TJ-Krebs.jpg?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2016\/01\/P1410349_Kellhuber-Foto-TJ-Krebs.jpg?fit=1200%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2016\/01\/P1410349_Kellhuber-Foto-TJ-Krebs.jpg?fit=1200%2C800&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2016\/01\/P1410349_Kellhuber-Foto-TJ-Krebs.jpg?fit=1200%2C800&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2016\/01\/P1410349_Kellhuber-Foto-TJ-Krebs.jpg?fit=1200%2C800&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":18156,"url":"https:\/\/www.jazzzeitung.de\/cms\/2018\/12\/magnetische-sternstunde-der-musik-das-lorenz-kellhuber-new-trio-im-stadttheater-regensburg\/","url_meta":{"origin":7911,"position":1},"title":"Magnetische Sternstunde der Musik: Das Lorenz Kellhuber New Trio im Stadttheater Regensburg","author":"Redaktion JazzZeitung","date":"21. Dezember 2018","format":false,"excerpt":"Regensburg. Verpufft, beiseite geschoben, weggewischt. Jeglicher Vorbehalt, ob ein reines Instrumentalkonzert bei den Zuh\u00f6rern auch ankommt, war schlussendlich atomisiert. Anf\u00e4nglich sorgte sich Pianist Lorenz Kellhuber im Theater Regensburg noch, dass Besucher sein Konzert mit dem New Trio vorzeitig verlassen k\u00f6nnten. Am Ende konnte die euphorisierte Menge kaum noch mit Zugaben\u2026","rel":"","context":"In &quot;Bericht&quot;","block_context":{"text":"Bericht","link":"https:\/\/www.jazzzeitung.de\/cms\/thema\/bericht\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2018\/12\/Trio-Kellhuber_37.jpeg?fit=567%2C370&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2018\/12\/Trio-Kellhuber_37.jpeg?fit=567%2C370&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2018\/12\/Trio-Kellhuber_37.jpeg?fit=567%2C370&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":4323,"url":"https:\/\/www.jazzzeitung.de\/cms\/2014\/07\/lorenz-kellhuber-gewinnt-piano-solo-competition-des-montreux-jazz-festival\/","url_meta":{"origin":7911,"position":2},"title":"Lorenz Kellhuber gewinnt Piano Solo Competition des Montreux Jazz Festival","author":"Martin Hufner","date":"18. Juli 2014","format":false,"excerpt":"Lorenz Kellhuber konnte am Dienstag als erster Deutscher die Piano Solo Competition des Montreux Jazz Festival f\u00fcr sich entscheiden. Er setzte sich im Finale gegen acht weitere junge Talente aus der ganzen Welt durch. Zwei Tage zuvor spielte er noch beim Bayerischen Jazzweekend in Regensburg im Tobias-Meinhart-Quintett sowie der abendlichen\u2026","rel":"","context":"In &quot;News&quot;","block_context":{"text":"News","link":"https:\/\/www.jazzzeitung.de\/cms\/thema\/nachrichten\/"},"img":{"alt_text":"Lorenz Kellhuber in Regensburg 2014. Foto: Hufner","src":"https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2014\/07\/lorenz_kellhuber_2014_c_hufner.jpg?fit=1200%2C901&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2014\/07\/lorenz_kellhuber_2014_c_hufner.jpg?fit=1200%2C901&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2014\/07\/lorenz_kellhuber_2014_c_hufner.jpg?fit=1200%2C901&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2014\/07\/lorenz_kellhuber_2014_c_hufner.jpg?fit=1200%2C901&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2014\/07\/lorenz_kellhuber_2014_c_hufner.jpg?fit=1200%2C901&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":12618,"url":"https:\/\/www.jazzzeitung.de\/cms\/2017\/06\/lorenz-kellhubers-trio-standard-experience-interpretiert-klassiker-auf-ganz-neue-eigene-weise\/","url_meta":{"origin":7911,"position":3},"title":"Lorenz Kellhubers Trio \u201eStandard Experience\u201c interpretiert Klassiker auf ganz neue, eigene Weise","author":"Michael Scheiner","date":"12. Juni 2017","format":false,"excerpt":"Heimspiel. Wenn in Regensburg ein Konzert des Pianisten und Komponisten Lorenz Kellhuber im Veranstaltungskalender steht, sehen Kulturaficionados das automatisch als ein Heimspiel mit entsprechendem Vor(ur)teil an. Obwohl der Musiker selbst in Berlin und seine beiden Mitmusiker, mit denen er beim Jazzclub im Leeren Beutel gastierte, in Brooklyn in den Vereinigten\u2026","rel":"","context":"In &quot;Bericht&quot;","block_context":{"text":"Bericht","link":"https:\/\/www.jazzzeitung.de\/cms\/thema\/bericht\/"},"img":{"alt_text":"Lorenz Kellhuber. Foto: Michael Scheiner","src":"https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2017\/06\/Kellhuber-Lorenz_56.jpg?fit=1074%2C1200&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2017\/06\/Kellhuber-Lorenz_56.jpg?fit=1074%2C1200&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2017\/06\/Kellhuber-Lorenz_56.jpg?fit=1074%2C1200&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2017\/06\/Kellhuber-Lorenz_56.jpg?fit=1074%2C1200&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2017\/06\/Kellhuber-Lorenz_56.jpg?fit=1074%2C1200&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":27574,"url":"https:\/\/www.jazzzeitung.de\/cms\/2022\/06\/jazz-auf-schloss-hoefling-ein-sommerabend-der-ungewoehnlichen-art-mit-lorenz-kellhuber\/","url_meta":{"origin":7911,"position":4},"title":"Jazz auf Schloss H\u00f6fling &#8211; ein Sommerabend der ungew\u00f6hnlichen Art mit Lorenz Kellhuber","author":"Redaktion JazzZeitung","date":"22. Juni 2022","format":false,"excerpt":"Eine gute Mischung hat sich Hausherr Constantin Graf von Walderdorff f\u00fcr sein Openair im Schlosshof H\u00f6fling nahe Regensburg einfallen lassen. Der S\u00e4nger und Klarinettist, der sich vor f\u00fcnf Jahren aus seiner aktiven Musikerkarriere zur\u00fcckgezogen hat, kennt Axel Zwingenberger aus seinen Wiener Jahren. Der Boogie-Woogie-Star spielte am Freitag Abend, dem 17.\u2026","rel":"","context":"In &quot;Bericht&quot;","block_context":{"text":"Bericht","link":"https:\/\/www.jazzzeitung.de\/cms\/thema\/bericht\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2022\/06\/kellhuber_hoefling_gaisa-4-scaled.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2022\/06\/kellhuber_hoefling_gaisa-4-scaled.jpg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2022\/06\/kellhuber_hoefling_gaisa-4-scaled.jpg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2022\/06\/kellhuber_hoefling_gaisa-4-scaled.jpg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2022\/06\/kellhuber_hoefling_gaisa-4-scaled.jpg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":4257,"url":"https:\/\/www.jazzzeitung.de\/cms\/2014\/07\/bayerisches-jazzweekend-2014-details\/","url_meta":{"origin":7911,"position":5},"title":"Bayerisches Jazzweekend 2014 \u2013 Teil I (Galerie)","author":"Martin Hufner","date":"14. Juli 2014","format":false,"excerpt":"So ein Wochenende kann schon sehr lang sein. Und wenn man aus Kleinmachnow angefahren kommt, wird es k\u00fcrzer und k\u00fcrzer. Bei den vielen Veranstaltungen, die so ein Weekend zieren, ist es dann nicht so einfach, irgendwo ein Pl\u00e4tzchen zu finden, an dem es einen auch wirklich festh\u00e4lt. Garant daf\u00fcr ist\u2026","rel":"","context":"In &quot;Blog&quot;","block_context":{"text":"Blog","link":"https:\/\/www.jazzzeitung.de\/cms\/thema\/blog\/"},"img":{"alt_text":"Besetzung: Axel K\u00fchn (s,bcl), Andi Kissenbeck (p), Axel K\u00fchn (b), Bastian J\u00fctte (d). Foto: Petra Basche","src":"https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2014\/07\/Jazzweekend_2014_pb_very-kuehn-002.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2014\/07\/Jazzweekend_2014_pb_very-kuehn-002.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2014\/07\/Jazzweekend_2014_pb_very-kuehn-002.jpg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2014\/07\/Jazzweekend_2014_pb_very-kuehn-002.jpg?resize=700%2C400 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.jazzzeitung.de\/cms\/wp-json\/wp\/v2\/posts\/7911","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jazzzeitung.de\/cms\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jazzzeitung.de\/cms\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jazzzeitung.de\/cms\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jazzzeitung.de\/cms\/wp-json\/wp\/v2\/comments?post=7911"}],"version-history":[{"count":4,"href":"https:\/\/www.jazzzeitung.de\/cms\/wp-json\/wp\/v2\/posts\/7911\/revisions"}],"predecessor-version":[{"id":7917,"href":"https:\/\/www.jazzzeitung.de\/cms\/wp-json\/wp\/v2\/posts\/7911\/revisions\/7917"}],"wp:attachment":[{"href":"https:\/\/www.jazzzeitung.de\/cms\/wp-json\/wp\/v2\/media?parent=7911"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jazzzeitung.de\/cms\/wp-json\/wp\/v2\/categories?post=7911"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jazzzeitung.de\/cms\/wp-json\/wp\/v2\/tags?post=7911"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jazzzeitung.de\/cms\/wp-json\/wp\/v2\/coauthors?post=7911"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}