{"id":20955,"date":"2019-10-23T09:48:49","date_gmt":"2019-10-23T07:48:49","guid":{"rendered":"https:\/\/www.jazzzeitung.de\/cms\/?p=20955"},"modified":"2019-10-23T09:48:49","modified_gmt":"2019-10-23T07:48:49","slug":"lisa-simone-mit-neuem-album","status":"publish","type":"post","link":"https:\/\/www.jazzzeitung.de\/cms\/2019\/10\/lisa-simone-mit-neuem-album\/","title":{"rendered":"Lisa Simone mit neuem Album"},"content":{"rendered":"<p><strong>Bei Priesterinnen w\u00fcrde man sagen sie ist eine Sp\u00e4tberufene. Bei Lisa Simone trifft das nur eingeschr\u00e4nkt zu, obwohl sie erst als 50-J\u00e4hrige ihre Solokarriere startete und in ihrem zweiten Album (My World) die eigene, von Ablehnung, \u00c4ngsten und Aufbegehren durchzogene Welt beschrieben hat. Bevor sie mit dem neuen Album endlich zu ihren Themen und einem pers\u00f6nlichen Ausdruck gefunden hat, musste Simone sich zun\u00e4chst von ihrer alles \u00fcberstrahlenden Mutter abgrenzen, der gro\u00dfen Nina Simone. Dazu musste sie mit ihrer Vergangenheit radikal brechen.<\/strong><\/p>\n<h3>Mit ihrem neuen Album \u201eIn Need Of Love\u201c macht die S\u00e4ngerin\u00a0 endlich Frieden mit ihrer ber\u00fchmten Mutter Nina Simone.<\/h3>\n<p>Lisa Simone hatte eine schwierige Kindheit und litt unter den Psychosen der Mutter ebenso, wie unter deren Zorn und aufgestauter Wut gegen\u00fcber dem allt\u00e4glichen Rassismus in den USA. Dann war Lisa auch noch h\u00e4ufig von ihrer Mom getrennt, die als internationaler Star viel in der Welt unterwegs war. Sie wurde haupts\u00e4chlich von Nannies und ihrer Tante Betty Shabazz betreut und aufgezogen, denn die Eltern liessen sich scheiden, als sie zehn Jahre alt war. Mit zwanzig ging sie zur Armee, diente bei der Air Force in Frankfurt und war an einem Einsatz im Irak beteiligt. Nach ihrer Milit\u00e4rzeit begann sie zu singen, zun\u00e4chst als Backgrounds\u00e4ngerin und sp\u00e4ter in verschiedenen Musicals als Schauspielerin und S\u00e4ngerin. Erst 2014 brachte sie ihr erstes Soloalbum heraus, das sie wie auch die folgenden zusammen mit dem franz\u00f6sischen Gitarristen, Komponisten und Arrangeur Herv\u00e9 Samb geschrieben hat.<\/p>\n<p><a href=\"https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2019\/10\/Lisa-Simone-PR-Foto-Credit-Warner-Music-1.jpeg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"20957\" data-permalink=\"https:\/\/www.jazzzeitung.de\/cms\/2019\/10\/lisa-simone-mit-neuem-album\/lisa-simone-pr-foto-credit-warner-music-1\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2019\/10\/Lisa-Simone-PR-Foto-Credit-Warner-Music-1.jpeg?fit=335%2C488&amp;ssl=1\" data-orig-size=\"335,488\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Lisa Simone PR Foto Credit Warner Music 1\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2019\/10\/Lisa-Simone-PR-Foto-Credit-Warner-Music-1.jpeg?fit=335%2C488&amp;ssl=1\" class=\"alignleft size-full wp-image-20957\" src=\"https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2019\/10\/Lisa-Simone-PR-Foto-Credit-Warner-Music-1.jpeg?resize=335%2C488&#038;ssl=1\" alt=\"\" width=\"335\" height=\"488\" srcset=\"https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2019\/10\/Lisa-Simone-PR-Foto-Credit-Warner-Music-1.jpeg?w=335&amp;ssl=1 335w, https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2019\/10\/Lisa-Simone-PR-Foto-Credit-Warner-Music-1.jpeg?resize=206%2C300&amp;ssl=1 206w\" sizes=\"auto, (max-width: 335px) 100vw, 335px\" \/><\/a><\/p>\n<h3><\/h3>\n<h3>Songs voller Tiefen und H\u00f6hen<\/h3>\n<p>Machte Lisa auf dem Vorg\u00e4ngeralbum reinen Tisch, klingt sie heute freier und in Songs, in denen sie Bezug auf die Mutter Nina nimmt, viel vers\u00f6hnlicher und verst\u00e4ndnisvoll. Geradezu z\u00e4rtlich singt sie mit leicht rauchiger Stimme in \u201eIn Need Of Love\u201c von den Dingen, die eine Frau durchgemacht hat \u2013 und eigentlich nur eines braucht, Liebe. Wobei offen bleibt, \u00fcber wen sie singt. Mit dieser wundervollen Popballade kann sie sowohl sich selbst, wie ihre Mutter oder Frauen allgemein meinen, die unter problematischen Lebensumst\u00e4nden zu leiden haben. Musikalisch ist der von einer akustischen Gitarre, Schlagzeug und Bass getragene Song simpel und nach vertrauten Mustern gestaltet, ohne ins Sentimentale oder gar in Belanglosigkeit abzudriften. Durchzogen von W\u00e4rme und Redlichkeit wirkt er authentisch und aufrichtig, wie das ganze\u00a0 Album.<\/p>\n<p>&nbsp;<\/p>\n<p>In \u201eGhost\u201c, das von einem pulsierenden Herzrhythmus getragen ist, fragt sie: \u201eDid you ever really love me\u201c, das habe sie nie wirklich gewu\u00dft, \u201eweil deine Art und Weise es zu zeigen, mich atemlos gemacht hat\u201c. Mit einer tief anr\u00fchrenden Stimme aus br\u00fcchiger Tiefe und von flirrender H\u00f6he hinterfragt sie noch einmal die Beziehung zu ihrer Mutter, die sie vor jedem besch\u00fctzt hat, nur nicht vor ihr selbst \u2013 eine \u201eschmerzvolle Liebe\u201c. Wie weit sie die Vergangenheit und ihre Schmerzen aufgearbeitet und zu einem heiter-gelassenen \u00a0\u00a0Selbstbewusstsein gefunden hat, zeigt sie im poppig perlenden \u201eWonderful\u201c. \u201eI`m wonderful, yes I`m wonderful\u201c, verwehrt sie sich gegen negative Stimmungsmache, begleitet von ihrem Sohn am Keyboard.<\/p>\n<h3>Soul, Gospel und Blues<\/h3>\n<p>Musikalisch ist auf dem vorwiegend akustisch eingespielten Album mit den zw\u00f6lf Songs eine ganze Menge los. W\u00e4rmender Soul, Gospel in Vokalarrangements, Blues, entr\u00fcckter Reggae und immer wieder moderne afrikanische Elemente wechseln mit kr\u00e4ftig pulsierendem Mainstream-Rock und funky Retrosounds. Eine Musik die mitnimmt, sich gelegentlich einschmeichelt, getragen von einer sinnlichen und jung wirkenden Stimme, die Gef\u00fchle bis in tiefste Tiefen und h\u00f6chste H\u00f6hen zu durchmessen imstande ist.<\/p>\n<p>Lisa Simone: In Need Of Love, CD und Download, Warner Music Int., 17,09 Euro (Audio)<\/p>\n<p><a href=\"https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2019\/10\/cover-Lisa-Simone-In-Need-Of-Love-.jpeg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"20956\" data-permalink=\"https:\/\/www.jazzzeitung.de\/cms\/2019\/10\/lisa-simone-mit-neuem-album\/cover-lisa-simone-in-need-of-love\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2019\/10\/cover-Lisa-Simone-In-Need-Of-Love-.jpeg?fit=961%2C961&amp;ssl=1\" data-orig-size=\"961,961\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"cover Lisa Simone &amp;#8211; In Need Of Love\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2019\/10\/cover-Lisa-Simone-In-Need-Of-Love-.jpeg?fit=600%2C600&amp;ssl=1\" class=\"alignleft size-medium wp-image-20956\" src=\"https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2019\/10\/cover-Lisa-Simone-In-Need-Of-Love-.jpeg?resize=300%2C300&#038;ssl=1\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2019\/10\/cover-Lisa-Simone-In-Need-Of-Love-.jpeg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2019\/10\/cover-Lisa-Simone-In-Need-Of-Love-.jpeg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2019\/10\/cover-Lisa-Simone-In-Need-Of-Love-.jpeg?resize=768%2C768&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2019\/10\/cover-Lisa-Simone-In-Need-Of-Love-.jpeg?resize=600%2C600&amp;ssl=1 600w, https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2019\/10\/cover-Lisa-Simone-In-Need-Of-Love-.jpeg?w=961&amp;ssl=1 961w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Info: <strong>Lisa Simone<\/strong> hat erst 50-j\u00e4hrig eine Karriere als Jazzs\u00e4ngerin begonnen. W\u00e4hrend ihrer Kindheit lebte sie \u00fcberall auf der Welt, da ihre Mutter unter anderem in Liberia und Frankreich lebte. Lisa Simone diente in der US-Armee und begann danach in der Jazzband Liquid Soul zu singen und auf dem New Yorker Broadway aufzutreten.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bei Priesterinnen w\u00fcrde man sagen sie ist eine Sp\u00e4tberufene. Bei Lisa Simone trifft das nur eingeschr\u00e4nkt zu, obwohl sie erst als 50-J\u00e4hrige ihre Solokarriere startete und in ihrem zweiten Album (My World) die eigene, von Ablehnung, \u00c4ngsten und Aufbegehren durchzogene Welt beschrieben hat. Bevor sie mit dem neuen Album endlich zu ihren Themen und einem pers\u00f6nlichen Ausdruck gefunden hat, musste Simone sich zun\u00e4chst von ihrer alles \u00fcberstrahlenden Mutter abgrenzen, der gro\u00dfen Nina Simone. Dazu musste sie mit ihrer Vergangenheit radikal brechen. Mit ihrem neuen Album \u201eIn Need Of Love\u201c macht die S\u00e4ngerin\u00a0 endlich Frieden mit ihrer ber\u00fchmten Mutter Nina Simone. Lisa Simone hatte eine schwierige Kindheit und litt unter den Psychosen der Mutter ebenso, wie unter deren Zorn und aufgestauter Wut gegen\u00fcber dem allt\u00e4glichen Rassismus in den USA. Dann war Lisa auch noch h\u00e4ufig von ihrer Mom getrennt, die als internationaler Star viel in der Welt unterwegs war. Sie wurde haupts\u00e4chlich von Nannies und ihrer Tante Betty Shabazz betreut und aufgezogen, denn die Eltern liessen sich scheiden, als sie zehn Jahre alt war. Mit zwanzig ging sie zur Armee, diente bei der Air Force in &hellip;<\/p>\n","protected":false},"author":37,"featured_media":20959,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[1152],"tags":[2801,2802,2800,387,2803],"coauthors":[1765],"class_list":["post-20955","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rezension","tag-in-need-of-love","tag-liquid-soul","tag-lisa-simone","tag-michael-scheiner","tag-nina-simone"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lisa Simone mit neuem Album - JazzZeitung<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.jazzzeitung.de\/cms\/2019\/10\/lisa-simone-mit-neuem-album\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lisa Simone mit neuem Album - JazzZeitung\" \/>\n<meta property=\"og:description\" content=\"Bei Priesterinnen w\u00fcrde man sagen sie ist eine Sp\u00e4tberufene. Bei Lisa Simone trifft das nur eingeschr\u00e4nkt zu, obwohl sie erst als 50-J\u00e4hrige ihre Solokarriere startete und in ihrem zweiten Album (My World) die eigene, von Ablehnung, \u00c4ngsten und Aufbegehren durchzogene Welt beschrieben hat. Bevor sie mit dem neuen Album endlich zu ihren Themen und einem pers\u00f6nlichen Ausdruck gefunden hat, musste Simone sich zun\u00e4chst von ihrer alles \u00fcberstrahlenden Mutter abgrenzen, der gro\u00dfen Nina Simone. Dazu musste sie mit ihrer Vergangenheit radikal brechen. Mit ihrem neuen Album \u201eIn Need Of Love\u201c macht die S\u00e4ngerin\u00a0 endlich Frieden mit ihrer ber\u00fchmten Mutter Nina Simone. Lisa Simone hatte eine schwierige Kindheit und litt unter den Psychosen der Mutter ebenso, wie unter deren Zorn und aufgestauter Wut gegen\u00fcber dem allt\u00e4glichen Rassismus in den USA. Dann war Lisa auch noch h\u00e4ufig von ihrer Mom getrennt, die als internationaler Star viel in der Welt unterwegs war. Sie wurde haupts\u00e4chlich von Nannies und ihrer Tante Betty Shabazz betreut und aufgezogen, denn die Eltern liessen sich scheiden, als sie zehn Jahre alt war. Mit zwanzig ging sie zur Armee, diente bei der Air Force in &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.jazzzeitung.de\/cms\/2019\/10\/lisa-simone-mit-neuem-album\/\" \/>\n<meta property=\"og:site_name\" content=\"JazzZeitung\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/JazzZeitung\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-10-23T07:48:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2019\/10\/Lisa-Simone-PR-Foto-Credit-Warner-Music-3.jpeg?fit=522%2C348&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"522\" \/>\n\t<meta property=\"og:image:height\" content=\"348\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Michael Scheiner\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.jazzzeitung.de\\\/cms\\\/2019\\\/10\\\/lisa-simone-mit-neuem-album\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jazzzeitung.de\\\/cms\\\/2019\\\/10\\\/lisa-simone-mit-neuem-album\\\/\"},\"author\":{\"name\":\"Michael Scheiner\",\"@id\":\"https:\\\/\\\/www.jazzzeitung.de\\\/cms\\\/#\\\/schema\\\/person\\\/a0bebd4d1728041629a3cbd7790f87fb\"},\"headline\":\"Lisa Simone mit neuem Album\",\"datePublished\":\"2019-10-23T07:48:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.jazzzeitung.de\\\/cms\\\/2019\\\/10\\\/lisa-simone-mit-neuem-album\\\/\"},\"wordCount\":662,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.jazzzeitung.de\\\/cms\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.jazzzeitung.de\\\/cms\\\/2019\\\/10\\\/lisa-simone-mit-neuem-album\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.jazzzeitung.de\\\/cms\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/Lisa-Simone-PR-Foto-Credit-Warner-Music-3.jpeg?fit=522%2C348&ssl=1\",\"keywords\":[\"In Need Of Love\",\"Liquid Soul\",\"Lisa Simone\",\"Michael Scheiner\",\"Nina Simone\"],\"articleSection\":[\"Rezension\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.jazzzeitung.de\\\/cms\\\/2019\\\/10\\\/lisa-simone-mit-neuem-album\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.jazzzeitung.de\\\/cms\\\/2019\\\/10\\\/lisa-simone-mit-neuem-album\\\/\",\"url\":\"https:\\\/\\\/www.jazzzeitung.de\\\/cms\\\/2019\\\/10\\\/lisa-simone-mit-neuem-album\\\/\",\"name\":\"Lisa Simone mit neuem Album - JazzZeitung\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jazzzeitung.de\\\/cms\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.jazzzeitung.de\\\/cms\\\/2019\\\/10\\\/lisa-simone-mit-neuem-album\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.jazzzeitung.de\\\/cms\\\/2019\\\/10\\\/lisa-simone-mit-neuem-album\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.jazzzeitung.de\\\/cms\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/Lisa-Simone-PR-Foto-Credit-Warner-Music-3.jpeg?fit=522%2C348&ssl=1\",\"datePublished\":\"2019-10-23T07:48:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.jazzzeitung.de\\\/cms\\\/2019\\\/10\\\/lisa-simone-mit-neuem-album\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.jazzzeitung.de\\\/cms\\\/2019\\\/10\\\/lisa-simone-mit-neuem-album\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.jazzzeitung.de\\\/cms\\\/2019\\\/10\\\/lisa-simone-mit-neuem-album\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.jazzzeitung.de\\\/cms\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/Lisa-Simone-PR-Foto-Credit-Warner-Music-3.jpeg?fit=522%2C348&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.jazzzeitung.de\\\/cms\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/Lisa-Simone-PR-Foto-Credit-Warner-Music-3.jpeg?fit=522%2C348&ssl=1\",\"width\":522,\"height\":348},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.jazzzeitung.de\\\/cms\\\/2019\\\/10\\\/lisa-simone-mit-neuem-album\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.jazzzeitung.de\\\/cms\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lisa Simone mit neuem Album\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.jazzzeitung.de\\\/cms\\\/#website\",\"url\":\"https:\\\/\\\/www.jazzzeitung.de\\\/cms\\\/\",\"name\":\"JazzZeitung\",\"description\":\"Jazz-News und Jazz-Kontroverses\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.jazzzeitung.de\\\/cms\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.jazzzeitung.de\\\/cms\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.jazzzeitung.de\\\/cms\\\/#organization\",\"name\":\"JazzZeitung online\",\"url\":\"https:\\\/\\\/www.jazzzeitung.de\\\/cms\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.jazzzeitung.de\\\/cms\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.jazzzeitung.de\\\/cms\\\/wp-content\\\/uploads\\\/2015\\\/08\\\/JAZZZEITUNGDE_Logo_Neu.png?fit=499%2C200&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.jazzzeitung.de\\\/cms\\\/wp-content\\\/uploads\\\/2015\\\/08\\\/JAZZZEITUNGDE_Logo_Neu.png?fit=499%2C200&ssl=1\",\"width\":499,\"height\":200,\"caption\":\"JazzZeitung online\"},\"image\":{\"@id\":\"https:\\\/\\\/www.jazzzeitung.de\\\/cms\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/JazzZeitung\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.jazzzeitung.de\\\/cms\\\/#\\\/schema\\\/person\\\/a0bebd4d1728041629a3cbd7790f87fb\",\"name\":\"Michael Scheiner\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c2d6ac12f682c419867cf3f803880bb41d5b23007d3670820aa9a6e7b5f6ec8d?s=96&d=wp_user_avatar&r=gdabb1b10453880983dfc53da7552ec76\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c2d6ac12f682c419867cf3f803880bb41d5b23007d3670820aa9a6e7b5f6ec8d?s=96&d=wp_user_avatar&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c2d6ac12f682c419867cf3f803880bb41d5b23007d3670820aa9a6e7b5f6ec8d?s=96&d=wp_user_avatar&r=g\",\"caption\":\"Michael Scheiner\"},\"sameAs\":[\"http:\\\/\\\/www.michaelscheiner.de\"],\"url\":\"https:\\\/\\\/www.jazzzeitung.de\\\/cms\\\/author\\\/mscheiner\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lisa Simone mit neuem Album - JazzZeitung","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.jazzzeitung.de\/cms\/2019\/10\/lisa-simone-mit-neuem-album\/","og_locale":"de_DE","og_type":"article","og_title":"Lisa Simone mit neuem Album - JazzZeitung","og_description":"Bei Priesterinnen w\u00fcrde man sagen sie ist eine Sp\u00e4tberufene. Bei Lisa Simone trifft das nur eingeschr\u00e4nkt zu, obwohl sie erst als 50-J\u00e4hrige ihre Solokarriere startete und in ihrem zweiten Album (My World) die eigene, von Ablehnung, \u00c4ngsten und Aufbegehren durchzogene Welt beschrieben hat. Bevor sie mit dem neuen Album endlich zu ihren Themen und einem pers\u00f6nlichen Ausdruck gefunden hat, musste Simone sich zun\u00e4chst von ihrer alles \u00fcberstrahlenden Mutter abgrenzen, der gro\u00dfen Nina Simone. Dazu musste sie mit ihrer Vergangenheit radikal brechen. Mit ihrem neuen Album \u201eIn Need Of Love\u201c macht die S\u00e4ngerin\u00a0 endlich Frieden mit ihrer ber\u00fchmten Mutter Nina Simone. Lisa Simone hatte eine schwierige Kindheit und litt unter den Psychosen der Mutter ebenso, wie unter deren Zorn und aufgestauter Wut gegen\u00fcber dem allt\u00e4glichen Rassismus in den USA. Dann war Lisa auch noch h\u00e4ufig von ihrer Mom getrennt, die als internationaler Star viel in der Welt unterwegs war. Sie wurde haupts\u00e4chlich von Nannies und ihrer Tante Betty Shabazz betreut und aufgezogen, denn die Eltern liessen sich scheiden, als sie zehn Jahre alt war. Mit zwanzig ging sie zur Armee, diente bei der Air Force in &hellip;","og_url":"https:\/\/www.jazzzeitung.de\/cms\/2019\/10\/lisa-simone-mit-neuem-album\/","og_site_name":"JazzZeitung","article_publisher":"https:\/\/www.facebook.com\/JazzZeitung\/","article_published_time":"2019-10-23T07:48:49+00:00","og_image":[{"width":522,"height":348,"url":"https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2019\/10\/Lisa-Simone-PR-Foto-Credit-Warner-Music-3.jpeg?fit=522%2C348&ssl=1","type":"image\/jpeg"}],"author":"Michael Scheiner","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.jazzzeitung.de\/cms\/2019\/10\/lisa-simone-mit-neuem-album\/#article","isPartOf":{"@id":"https:\/\/www.jazzzeitung.de\/cms\/2019\/10\/lisa-simone-mit-neuem-album\/"},"author":{"name":"Michael Scheiner","@id":"https:\/\/www.jazzzeitung.de\/cms\/#\/schema\/person\/a0bebd4d1728041629a3cbd7790f87fb"},"headline":"Lisa Simone mit neuem Album","datePublished":"2019-10-23T07:48:49+00:00","mainEntityOfPage":{"@id":"https:\/\/www.jazzzeitung.de\/cms\/2019\/10\/lisa-simone-mit-neuem-album\/"},"wordCount":662,"commentCount":0,"publisher":{"@id":"https:\/\/www.jazzzeitung.de\/cms\/#organization"},"image":{"@id":"https:\/\/www.jazzzeitung.de\/cms\/2019\/10\/lisa-simone-mit-neuem-album\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2019\/10\/Lisa-Simone-PR-Foto-Credit-Warner-Music-3.jpeg?fit=522%2C348&ssl=1","keywords":["In Need Of Love","Liquid Soul","Lisa Simone","Michael Scheiner","Nina Simone"],"articleSection":["Rezension"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.jazzzeitung.de\/cms\/2019\/10\/lisa-simone-mit-neuem-album\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.jazzzeitung.de\/cms\/2019\/10\/lisa-simone-mit-neuem-album\/","url":"https:\/\/www.jazzzeitung.de\/cms\/2019\/10\/lisa-simone-mit-neuem-album\/","name":"Lisa Simone mit neuem Album - JazzZeitung","isPartOf":{"@id":"https:\/\/www.jazzzeitung.de\/cms\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.jazzzeitung.de\/cms\/2019\/10\/lisa-simone-mit-neuem-album\/#primaryimage"},"image":{"@id":"https:\/\/www.jazzzeitung.de\/cms\/2019\/10\/lisa-simone-mit-neuem-album\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2019\/10\/Lisa-Simone-PR-Foto-Credit-Warner-Music-3.jpeg?fit=522%2C348&ssl=1","datePublished":"2019-10-23T07:48:49+00:00","breadcrumb":{"@id":"https:\/\/www.jazzzeitung.de\/cms\/2019\/10\/lisa-simone-mit-neuem-album\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.jazzzeitung.de\/cms\/2019\/10\/lisa-simone-mit-neuem-album\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.jazzzeitung.de\/cms\/2019\/10\/lisa-simone-mit-neuem-album\/#primaryimage","url":"https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2019\/10\/Lisa-Simone-PR-Foto-Credit-Warner-Music-3.jpeg?fit=522%2C348&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2019\/10\/Lisa-Simone-PR-Foto-Credit-Warner-Music-3.jpeg?fit=522%2C348&ssl=1","width":522,"height":348},{"@type":"BreadcrumbList","@id":"https:\/\/www.jazzzeitung.de\/cms\/2019\/10\/lisa-simone-mit-neuem-album\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.jazzzeitung.de\/cms\/"},{"@type":"ListItem","position":2,"name":"Lisa Simone mit neuem Album"}]},{"@type":"WebSite","@id":"https:\/\/www.jazzzeitung.de\/cms\/#website","url":"https:\/\/www.jazzzeitung.de\/cms\/","name":"JazzZeitung","description":"Jazz-News und Jazz-Kontroverses","publisher":{"@id":"https:\/\/www.jazzzeitung.de\/cms\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.jazzzeitung.de\/cms\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.jazzzeitung.de\/cms\/#organization","name":"JazzZeitung online","url":"https:\/\/www.jazzzeitung.de\/cms\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.jazzzeitung.de\/cms\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2015\/08\/JAZZZEITUNGDE_Logo_Neu.png?fit=499%2C200&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2015\/08\/JAZZZEITUNGDE_Logo_Neu.png?fit=499%2C200&ssl=1","width":499,"height":200,"caption":"JazzZeitung online"},"image":{"@id":"https:\/\/www.jazzzeitung.de\/cms\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/JazzZeitung\/"]},{"@type":"Person","@id":"https:\/\/www.jazzzeitung.de\/cms\/#\/schema\/person\/a0bebd4d1728041629a3cbd7790f87fb","name":"Michael Scheiner","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/c2d6ac12f682c419867cf3f803880bb41d5b23007d3670820aa9a6e7b5f6ec8d?s=96&d=wp_user_avatar&r=gdabb1b10453880983dfc53da7552ec76","url":"https:\/\/secure.gravatar.com\/avatar\/c2d6ac12f682c419867cf3f803880bb41d5b23007d3670820aa9a6e7b5f6ec8d?s=96&d=wp_user_avatar&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c2d6ac12f682c419867cf3f803880bb41d5b23007d3670820aa9a6e7b5f6ec8d?s=96&d=wp_user_avatar&r=g","caption":"Michael Scheiner"},"sameAs":["http:\/\/www.michaelscheiner.de"],"url":"https:\/\/www.jazzzeitung.de\/cms\/author\/mscheiner\/"}]}},"wp-worthy-pixel":{"ignored":false,"public":null,"server":null,"url":null},"wp-worthy-type":"normal","jetpack_publicize_connections":[],"cc_featured_image_caption":{"caption_text":"","source_text":"","source_url":""},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2019\/10\/Lisa-Simone-PR-Foto-Credit-Warner-Music-3.jpeg?fit=522%2C348&ssl=1","jetpack_shortlink":"https:\/\/wp.me\/p3KEcT-5rZ","jetpack-related-posts":[{"id":17970,"url":"https:\/\/www.jazzzeitung.de\/cms\/2018\/11\/malias-momente-voller-intimitaet-und-intensitaet\/","url_meta":{"origin":20955,"position":0},"title":"Malias Momente voller Intimit\u00e4t und Intensit\u00e4t","author":"Redaktion JazzZeitung","date":"28. November 2018","format":false,"excerpt":"Von Michael Scheiner. Etwas radikal Neues oder eine ganz neue Richtung, die mit einem neuen Album eingeschlagen worden sei, wird gerade im Schlager, Pop und Songwritertum \u00f6fter einmal von Musikern angek\u00fcndigt. Im Ergebnis stellt es sich dann allzuoft eher als Variation, kleine Erweiterung oder Qu\u00e4ntchen mehr des Bisherigen heraus. Auch\u2026","rel":"","context":"In &quot;Bericht&quot;","block_context":{"text":"Bericht","link":"https:\/\/www.jazzzeitung.de\/cms\/thema\/bericht\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2018\/11\/Malia_39.jpeg?fit=567%2C378&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2018\/11\/Malia_39.jpeg?fit=567%2C378&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2018\/11\/Malia_39.jpeg?fit=567%2C378&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":7819,"url":"https:\/\/www.jazzzeitung.de\/cms\/2015\/11\/7819\/","url_meta":{"origin":20955,"position":1},"title":"Jazzfest Bonn 2016 legt Schwerpunkt auf Klavier und Gesang","author":"Redaktion JazzZeitung","date":"26. November 2015","format":false,"excerpt":"Das neue Jahr r\u00fcckt n\u00e4her und es wird Zeit, sich die Termine der zentralen Festivals im Kalender zu blocken. Seit heute ist das Programm des Jazzfest Bonn online, das wieder einmal gewachsen ist. In seinem siebten Jahr pr\u00e4sentiert Festivalchef Peter Materna und sein Team Jazz an elf Konzertabenden, verteilt \u00fcber\u2026","rel":"","context":"In &quot;News&quot;","block_context":{"text":"News","link":"https:\/\/www.jazzzeitung.de\/cms\/thema\/nachrichten\/"},"img":{"alt_text":"JfB16ProgrammFINlay","src":"https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2015\/11\/JfB16ProgrammFINlay-150x150.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":21816,"url":"https:\/\/www.jazzzeitung.de\/cms\/2020\/01\/wie-man-opener-bei-der-jazzopen-stuttgart-werden-kann\/","url_meta":{"origin":20955,"position":2},"title":"Wie man Opener bei der jazzopen-Stuttgart werden kann","author":"Redaktion JazzZeitung","date":"30. Januar 2020","format":false,"excerpt":"Das Festival jazzopen in Stuttgart hat sein Programm bekanntgegeben und mit dem Vorverkauf begonnen. Bevor hier mehr \u00fcber die K\u00fcnstler der Festivalausgabe 2020 gesagt wird, ein Hinweis auf eine Bewerbungsfrist: Der vom Land Baden-W\u00fcrttemberg unterst\u00fctzte Bandnachwuchs-Wettbewerb \"playground BW\" wird auch in diesem Jahr ausgelobt. Einsendeschluss ist der 31. M\u00e4rz, die\u2026","rel":"","context":"In &quot;News&quot;","block_context":{"text":"News","link":"https:\/\/www.jazzzeitung.de\/cms\/thema\/nachrichten\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2017\/07\/034_JanDelay-DiskoNo.1_Foto-van-Loon.jpg?fit=1200%2C709&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2017\/07\/034_JanDelay-DiskoNo.1_Foto-van-Loon.jpg?fit=1200%2C709&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2017\/07\/034_JanDelay-DiskoNo.1_Foto-van-Loon.jpg?fit=1200%2C709&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2017\/07\/034_JanDelay-DiskoNo.1_Foto-van-Loon.jpg?fit=1200%2C709&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2017\/07\/034_JanDelay-DiskoNo.1_Foto-van-Loon.jpg?fit=1200%2C709&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":6086,"url":"https:\/\/www.jazzzeitung.de\/cms\/2015\/05\/rieke-katz-und-band-smooth-jazz-aus-nuernberg\/","url_meta":{"origin":20955,"position":3},"title":"\u201eRieke Katz und Band\u201c \u2013 Smooth Jazz aus N\u00fcrnberg","author":"Redaktion JazzZeitung","date":"8. Mai 2015","format":false,"excerpt":"Von Hannah W\u00fcrsching \u2013 \u201eAlles Neu macht der Mai\u201c, k\u00f6nnte auch ein Motto von \u201eRieke Katz und Band\u201c sein. Denn ihr erstes eigenes Album \u201eNew Start\u201c ist von Aufbruchsstimmung gepr\u00e4gt. \u201eRieke Katz und Band\u201c, das sind Rieke Katz (Gesang), Martin S\u00f6r\u00f6s (Klavier), Alexander Bayer (Bass), Bj\u00f6rn Glindermann (Schlagzeug) und Christoph\u2026","rel":"","context":"In &quot;Newcomer des Monats&quot;","block_context":{"text":"Newcomer des Monats","link":"https:\/\/www.jazzzeitung.de\/cms\/thema\/newcomer\/"},"img":{"alt_text":"Rieke Katz. Foto: Valentin Schilling","src":"https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2015\/05\/Portrait.jpg?fit=1200%2C801&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2015\/05\/Portrait.jpg?fit=1200%2C801&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2015\/05\/Portrait.jpg?fit=1200%2C801&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2015\/05\/Portrait.jpg?fit=1200%2C801&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2015\/05\/Portrait.jpg?fit=1200%2C801&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":26713,"url":"https:\/\/www.jazzzeitung.de\/cms\/2022\/02\/alma-naidu-mit-fulminantem-debut-album-alma\/","url_meta":{"origin":20955,"position":4},"title":"Alma Naidu mit fulminantem Debut Album: \u201eAlma\u201c","author":"Redaktion JazzZeitung","date":"11. Februar 2022","format":false,"excerpt":"Selbstbewusst schreitet die S\u00e4ngerin Alma Naidu auf ihrem Debut Album \u201eAlma\u201c durch ihren musikalischen Kosmos und begeistert nicht nur mit ihrer einzigartigen Stimme, sondern \u00fcberzeugt mit treffsicherem, kompositorischem Talent und einf\u00fchlsamen Texten. \u00a0Musik begleitet sie seit ihrer Geburt, der Vater Dirigent, die Mutter Operns\u00e4ngerin. Wenn Alma Naidu mit ihrer Stimme\u2026","rel":"","context":"In &quot;Rezension&quot;","block_context":{"text":"Rezension","link":"https:\/\/www.jazzzeitung.de\/cms\/thema\/rezension\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2022\/02\/P1332956-Naidu-HG-DE-Foto-TJ-Krebs.jpg?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2022\/02\/P1332956-Naidu-HG-DE-Foto-TJ-Krebs.jpg?fit=1200%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2022\/02\/P1332956-Naidu-HG-DE-Foto-TJ-Krebs.jpg?fit=1200%2C800&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2022\/02\/P1332956-Naidu-HG-DE-Foto-TJ-Krebs.jpg?fit=1200%2C800&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2022\/02\/P1332956-Naidu-HG-DE-Foto-TJ-Krebs.jpg?fit=1200%2C800&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":18099,"url":"https:\/\/www.jazzzeitung.de\/cms\/2018\/12\/stefanie-lottermoser-ein-lullabye-fuer-die-eltern\/","url_meta":{"origin":20955,"position":5},"title":"Stefanie Lottermoser &#8211; ein \u201eLullabye\u201c f\u00fcr die Eltern","author":"Redaktion JazzZeitung","date":"15. Dezember 2018","format":false,"excerpt":"Von Michael Scheiner, Regensburg. Zu mehr als einer Zugabe wollte sie sich nicht bewegen lassen. Doch die hatte es in sich. Bei Eddie Harris\u00b4 Komposition \u201eCold Duck Time\u201c, ein wahrlich kryptischer Titel, drehte die Saxofonistin Stephanie Lottermoser noch einmal richtig auf. Mit kurz heraus gesto\u00dfenen Noten befeuerte sie den leicht\u2026","rel":"","context":"In &quot;Bericht&quot;","block_context":{"text":"Bericht","link":"https:\/\/www.jazzzeitung.de\/cms\/thema\/bericht\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2018\/12\/Lottermoser-Stephanie_64.jpeg?fit=567%2C371&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2018\/12\/Lottermoser-Stephanie_64.jpeg?fit=567%2C371&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2018\/12\/Lottermoser-Stephanie_64.jpeg?fit=567%2C371&ssl=1&resize=525%2C300 1.5x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.jazzzeitung.de\/cms\/wp-json\/wp\/v2\/posts\/20955","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jazzzeitung.de\/cms\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jazzzeitung.de\/cms\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jazzzeitung.de\/cms\/wp-json\/wp\/v2\/users\/37"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jazzzeitung.de\/cms\/wp-json\/wp\/v2\/comments?post=20955"}],"version-history":[{"count":3,"href":"https:\/\/www.jazzzeitung.de\/cms\/wp-json\/wp\/v2\/posts\/20955\/revisions"}],"predecessor-version":[{"id":20962,"href":"https:\/\/www.jazzzeitung.de\/cms\/wp-json\/wp\/v2\/posts\/20955\/revisions\/20962"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jazzzeitung.de\/cms\/wp-json\/wp\/v2\/media\/20959"}],"wp:attachment":[{"href":"https:\/\/www.jazzzeitung.de\/cms\/wp-json\/wp\/v2\/media?parent=20955"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jazzzeitung.de\/cms\/wp-json\/wp\/v2\/categories?post=20955"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jazzzeitung.de\/cms\/wp-json\/wp\/v2\/tags?post=20955"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jazzzeitung.de\/cms\/wp-json\/wp\/v2\/coauthors?post=20955"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}