{"id":12156,"date":"2017-04-21T10:55:20","date_gmt":"2017-04-21T08:55:20","guid":{"rendered":"http:\/\/www.jazzzeitung.de\/cms\/?p=12156"},"modified":"2017-04-21T10:55:20","modified_gmt":"2017-04-21T08:55:20","slug":"essen-jazz-orchestra-am-30-april-in-der-casa-des-schauspiel-essen","status":"publish","type":"post","link":"https:\/\/www.jazzzeitung.de\/cms\/2017\/04\/essen-jazz-orchestra-am-30-april-in-der-casa-des-schauspiel-essen\/","title":{"rendered":"\u201eEssen-Jazz-Orchestra\u201c am 30. April in der Casa des Schauspiel Essen"},"content":{"rendered":"<figure id=\"attachment_12157\" aria-describedby=\"caption-attachment-12157\" style=\"width: 150px\" class=\"wp-caption alignright\"><a href=\"https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2017\/04\/Essen-Jazz-Orchestra_2.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"12157\" data-permalink=\"https:\/\/www.jazzzeitung.de\/cms\/2017\/04\/essen-jazz-orchestra-am-30-april-in-der-casa-des-schauspiel-essen\/essen-jazz-orchestra\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2017\/04\/Essen-Jazz-Orchestra_2.jpg?fit=3763%2C2239&amp;ssl=1\" data-orig-size=\"3763,2239\" data-comments-opened=\"1\" data-image-title=\"Essen-Jazz-Orchestra\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Das Essen-Jazz-Orchestra&lt;\/p&gt;\n\" data-large-file=\"https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2017\/04\/Essen-Jazz-Orchestra_2.jpg?fit=840%2C500&amp;ssl=1\" class=\"size-thumbnail wp-image-12157\" src=\"https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2017\/04\/Essen-Jazz-Orchestra_2-150x150.jpg?resize=150%2C150\" alt=\"\" width=\"150\" height=\"150\" srcset=\"https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2017\/04\/Essen-Jazz-Orchestra_2.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2017\/04\/Essen-Jazz-Orchestra_2.jpg?resize=144%2C144&amp;ssl=1 144w, https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2017\/04\/Essen-Jazz-Orchestra_2.jpg?resize=96%2C96&amp;ssl=1 96w, https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2017\/04\/Essen-Jazz-Orchestra_2.jpg?resize=24%2C24&amp;ssl=1 24w, https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2017\/04\/Essen-Jazz-Orchestra_2.jpg?resize=36%2C36&amp;ssl=1 36w, https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2017\/04\/Essen-Jazz-Orchestra_2.jpg?resize=48%2C48&amp;ssl=1 48w, https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2017\/04\/Essen-Jazz-Orchestra_2.jpg?resize=64%2C64&amp;ssl=1 64w, https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2017\/04\/Essen-Jazz-Orchestra_2.jpg?resize=32%2C32&amp;ssl=1 32w, https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2017\/04\/Essen-Jazz-Orchestra_2.jpg?resize=50%2C50&amp;ssl=1 50w, https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2017\/04\/Essen-Jazz-Orchestra_2.jpg?resize=128%2C128&amp;ssl=1 128w, https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2017\/04\/Essen-Jazz-Orchestra_2.jpg?zoom=2&amp;resize=150%2C150&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2017\/04\/Essen-Jazz-Orchestra_2.jpg?zoom=3&amp;resize=150%2C150&amp;ssl=1 450w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a><figcaption id=\"caption-attachment-12157\" class=\"wp-caption-text\">Das Essen-Jazz-Orchestra. Foto: Kurt Rade<\/figcaption><\/figure>\n<p><strong>Lange galten sie als die Elefanten unter den Jazz-Besetzungen, denn unter einem Dutzend Instrumentalisten kommt keine Big Band aus. Und auch das Image dieser Orchester war in den vergangenen Jahrzehnten eher durchwachsen: Da war die Rede von \u201eOpa-Musik\u201c und \u201eSchnee von gestern\u201c. Nachdem allerdings Robbie Williams seine Frank-Sinatra-Hommage \u201eSwing When You&#8217;re Winning\u201c herausgebracht hatte und Roger Cicero mit seinem Hitalbum \u201eM\u00e4nnersachen\u201c gro\u00dfe Erfolge feiern konnte, wendete sich das Blatt: Auch eine neue Generation von Musikern entdeckte die Klangkraft solcher Formationen f\u00fcr sich und experimentierte nach Lust und Laune in gro\u00dfer Besetzung.<\/strong><\/p>\n<p>Im Ruhrgebiet hat sich f\u00fcr Freunde des satten Big-Band-Sounds das \u201eEssen-Jazz-Orchestra\u201c mittlerweile zu einer festen Gr\u00f6\u00dfe entwickelt. Die Truppe, die aus Absolventen der Essener Folkwang Universit\u00e4t der K\u00fcnste und Musikern der freien Jazz-Szene Essens besteht, pr\u00e4sentiert bei ihren Konzerten vorrangig St\u00fccke, die von einigen Ensemblemitgliedern selbst komponiert wurden. Welche aktuellen Neukompositionen das <strong>\u201eEssen-Jazz-Orchestra\u201c<\/strong> unter der Leitung von Tobias Sch\u00fctte bei seinem n\u00e4chsten Auftritt <strong>am Sonntag, dem 30. April ab 19 Uhr in die Casa des Schauspiel Essen <\/strong>spielen wird, steht derzeit noch nicht fest, aber das ist sicher: Es gibt wieder reichlich Futter f\u00fcr die Ohren.<\/p>\n<p>Es spielen: Roman Sieweke, Felix Fritsche (Altsax), Veit Lange, Natalie Hausmann (Tenorsax), Florian Walter (Baritonsax), Tobias Wember, Raphael Klemm, Peter Schwatlo, Gerd Jentzsch (Posaunen), John-Dennis Renken, Jakob Helling, Stephan Struck, Sinje Schnittker, Martin Berner (Trompeten), Hermann Heidenreich (Drums), Andreas Wahl (Gitarre), Alex Morsey (Bass), Hajo Wiesemann (Klavier).<\/p>\n<p>Eintritt: \u20ac 8,00<\/p>\n<p><strong>Kartenvorverkauf: TicketCenter der Theater und Philharmonie Essen, Tel.: 0201\/81 22-200, oder unter <a href=\"mailto:tickets@theater-essen.de\">tickets@theater-essen.de<\/a><\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Termin: Sonntag, 30. April ab 19 Uhr in der Casa des Schauspiel Essen<\/strong>.<\/p>\n<p>Mehr Infos \u00fcber die Big Band unter <a href=\"http:\/\/e-j-o.de\/\">http:\/\/e-j-o.de<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lange galten sie als die Elefanten unter den Jazz-Besetzungen, denn unter einem Dutzend Instrumentalisten kommt keine Big Band aus. Und auch das Image dieser Orchester war in den vergangenen Jahrzehnten eher durchwachsen: Da war die Rede von \u201eOpa-Musik\u201c und \u201eSchnee von gestern\u201c. Nachdem allerdings Robbie Williams seine Frank-Sinatra-Hommage \u201eSwing When You&#8217;re Winning\u201c herausgebracht hatte und Roger Cicero mit seinem Hitalbum \u201eM\u00e4nnersachen\u201c gro\u00dfe Erfolge feiern konnte, wendete sich das Blatt: Auch eine neue Generation von Musikern entdeckte die Klangkraft solcher Formationen f\u00fcr sich und experimentierte nach Lust und Laune in gro\u00dfer Besetzung. Im Ruhrgebiet hat sich f\u00fcr Freunde des satten Big-Band-Sounds das \u201eEssen-Jazz-Orchestra\u201c mittlerweile zu einer festen Gr\u00f6\u00dfe entwickelt. Die Truppe, die aus Absolventen der Essener Folkwang Universit\u00e4t der K\u00fcnste und Musikern der freien Jazz-Szene Essens besteht, pr\u00e4sentiert bei ihren Konzerten vorrangig St\u00fccke, die von einigen Ensemblemitgliedern selbst komponiert wurden. Welche aktuellen Neukompositionen das \u201eEssen-Jazz-Orchestra\u201c unter der Leitung von Tobias Sch\u00fctte bei seinem n\u00e4chsten Auftritt am Sonntag, dem 30. April ab 19 Uhr in die Casa des Schauspiel Essen spielen wird, steht derzeit noch nicht fest, aber das ist sicher: Es gibt wieder reichlich Futter f\u00fcr &hellip;<\/p>\n","protected":false},"author":18,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[633],"tags":[71,691,472,535,548],"coauthors":[695],"class_list":["post-12156","post","type-post","status-publish","format-standard","hentry","category-nachrichten","tag-big-band","tag-essen","tag-robbie-williams","tag-swing","tag-tickets"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u201eEssen-Jazz-Orchestra\u201c am 30. April in der Casa des Schauspiel Essen - JazzZeitung<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.jazzzeitung.de\/cms\/2017\/04\/essen-jazz-orchestra-am-30-april-in-der-casa-des-schauspiel-essen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u201eEssen-Jazz-Orchestra\u201c am 30. April in der Casa des Schauspiel Essen - JazzZeitung\" \/>\n<meta property=\"og:description\" content=\"Lange galten sie als die Elefanten unter den Jazz-Besetzungen, denn unter einem Dutzend Instrumentalisten kommt keine Big Band aus. Und auch das Image dieser Orchester war in den vergangenen Jahrzehnten eher durchwachsen: Da war die Rede von \u201eOpa-Musik\u201c und \u201eSchnee von gestern\u201c. Nachdem allerdings Robbie Williams seine Frank-Sinatra-Hommage \u201eSwing When You&#8217;re Winning\u201c herausgebracht hatte und Roger Cicero mit seinem Hitalbum \u201eM\u00e4nnersachen\u201c gro\u00dfe Erfolge feiern konnte, wendete sich das Blatt: Auch eine neue Generation von Musikern entdeckte die Klangkraft solcher Formationen f\u00fcr sich und experimentierte nach Lust und Laune in gro\u00dfer Besetzung. Im Ruhrgebiet hat sich f\u00fcr Freunde des satten Big-Band-Sounds das \u201eEssen-Jazz-Orchestra\u201c mittlerweile zu einer festen Gr\u00f6\u00dfe entwickelt. Die Truppe, die aus Absolventen der Essener Folkwang Universit\u00e4t der K\u00fcnste und Musikern der freien Jazz-Szene Essens besteht, pr\u00e4sentiert bei ihren Konzerten vorrangig St\u00fccke, die von einigen Ensemblemitgliedern selbst komponiert wurden. Welche aktuellen Neukompositionen das \u201eEssen-Jazz-Orchestra\u201c unter der Leitung von Tobias Sch\u00fctte bei seinem n\u00e4chsten Auftritt am Sonntag, dem 30. April ab 19 Uhr in die Casa des Schauspiel Essen spielen wird, steht derzeit noch nicht fest, aber das ist sicher: Es gibt wieder reichlich Futter f\u00fcr &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.jazzzeitung.de\/cms\/2017\/04\/essen-jazz-orchestra-am-30-april-in-der-casa-des-schauspiel-essen\/\" \/>\n<meta property=\"og:site_name\" content=\"JazzZeitung\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/JazzZeitung\/\" \/>\n<meta property=\"article:published_time\" content=\"2017-04-21T08:55:20+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2017\/04\/Essen-Jazz-Orchestra_2-150x150.jpg\" \/>\n<meta name=\"author\" content=\"Redaktion JazzZeitung\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.jazzzeitung.de\\\/cms\\\/2017\\\/04\\\/essen-jazz-orchestra-am-30-april-in-der-casa-des-schauspiel-essen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jazzzeitung.de\\\/cms\\\/2017\\\/04\\\/essen-jazz-orchestra-am-30-april-in-der-casa-des-schauspiel-essen\\\/\"},\"author\":{\"name\":\"Redaktion JazzZeitung\",\"@id\":\"https:\\\/\\\/www.jazzzeitung.de\\\/cms\\\/#\\\/schema\\\/person\\\/2245b36b9cd1d24cea10f01c031fb92b\"},\"headline\":\"\u201eEssen-Jazz-Orchestra\u201c am 30. April in der Casa des Schauspiel Essen\",\"datePublished\":\"2017-04-21T08:55:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.jazzzeitung.de\\\/cms\\\/2017\\\/04\\\/essen-jazz-orchestra-am-30-april-in-der-casa-des-schauspiel-essen\\\/\"},\"wordCount\":304,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.jazzzeitung.de\\\/cms\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.jazzzeitung.de\\\/cms\\\/2017\\\/04\\\/essen-jazz-orchestra-am-30-april-in-der-casa-des-schauspiel-essen\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.jazzzeitung.de\\\/cms\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/Essen-Jazz-Orchestra_2-150x150.jpg\",\"keywords\":[\"Big Band\",\"Essen\",\"Robbie Williams\",\"Swing\",\"Tickets\"],\"articleSection\":[\"News\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.jazzzeitung.de\\\/cms\\\/2017\\\/04\\\/essen-jazz-orchestra-am-30-april-in-der-casa-des-schauspiel-essen\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.jazzzeitung.de\\\/cms\\\/2017\\\/04\\\/essen-jazz-orchestra-am-30-april-in-der-casa-des-schauspiel-essen\\\/\",\"url\":\"https:\\\/\\\/www.jazzzeitung.de\\\/cms\\\/2017\\\/04\\\/essen-jazz-orchestra-am-30-april-in-der-casa-des-schauspiel-essen\\\/\",\"name\":\"\u201eEssen-Jazz-Orchestra\u201c am 30. April in der Casa des Schauspiel Essen - JazzZeitung\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jazzzeitung.de\\\/cms\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.jazzzeitung.de\\\/cms\\\/2017\\\/04\\\/essen-jazz-orchestra-am-30-april-in-der-casa-des-schauspiel-essen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.jazzzeitung.de\\\/cms\\\/2017\\\/04\\\/essen-jazz-orchestra-am-30-april-in-der-casa-des-schauspiel-essen\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.jazzzeitung.de\\\/cms\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/Essen-Jazz-Orchestra_2-150x150.jpg\",\"datePublished\":\"2017-04-21T08:55:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.jazzzeitung.de\\\/cms\\\/2017\\\/04\\\/essen-jazz-orchestra-am-30-april-in-der-casa-des-schauspiel-essen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.jazzzeitung.de\\\/cms\\\/2017\\\/04\\\/essen-jazz-orchestra-am-30-april-in-der-casa-des-schauspiel-essen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.jazzzeitung.de\\\/cms\\\/2017\\\/04\\\/essen-jazz-orchestra-am-30-april-in-der-casa-des-schauspiel-essen\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.jazzzeitung.de\\\/cms\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/Essen-Jazz-Orchestra_2-150x150.jpg\",\"contentUrl\":\"http:\\\/\\\/www.jazzzeitung.de\\\/cms\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/Essen-Jazz-Orchestra_2-150x150.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.jazzzeitung.de\\\/cms\\\/2017\\\/04\\\/essen-jazz-orchestra-am-30-april-in-der-casa-des-schauspiel-essen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.jazzzeitung.de\\\/cms\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u201eEssen-Jazz-Orchestra\u201c am 30. April in der Casa des Schauspiel Essen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.jazzzeitung.de\\\/cms\\\/#website\",\"url\":\"https:\\\/\\\/www.jazzzeitung.de\\\/cms\\\/\",\"name\":\"JazzZeitung\",\"description\":\"Jazz-News und Jazz-Kontroverses\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.jazzzeitung.de\\\/cms\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.jazzzeitung.de\\\/cms\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.jazzzeitung.de\\\/cms\\\/#organization\",\"name\":\"JazzZeitung online\",\"url\":\"https:\\\/\\\/www.jazzzeitung.de\\\/cms\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.jazzzeitung.de\\\/cms\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.jazzzeitung.de\\\/cms\\\/wp-content\\\/uploads\\\/2015\\\/08\\\/JAZZZEITUNGDE_Logo_Neu.png?fit=499%2C200&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.jazzzeitung.de\\\/cms\\\/wp-content\\\/uploads\\\/2015\\\/08\\\/JAZZZEITUNGDE_Logo_Neu.png?fit=499%2C200&ssl=1\",\"width\":499,\"height\":200,\"caption\":\"JazzZeitung online\"},\"image\":{\"@id\":\"https:\\\/\\\/www.jazzzeitung.de\\\/cms\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/JazzZeitung\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.jazzzeitung.de\\\/cms\\\/#\\\/schema\\\/person\\\/2245b36b9cd1d24cea10f01c031fb92b\",\"name\":\"Redaktion JazzZeitung\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/i0.wp.com\\\/www.jazzzeitung.de\\\/cms\\\/wp-content\\\/uploads\\\/2015\\\/08\\\/JAZZZEITUNGDE_Logo_Neu.png?resize=96%2C96&ssl=159975dcacb611b5700bd619b5daf0a7a\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.jazzzeitung.de\\\/cms\\\/wp-content\\\/uploads\\\/2015\\\/08\\\/JAZZZEITUNGDE_Logo_Neu.png?resize=96%2C96&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.jazzzeitung.de\\\/cms\\\/wp-content\\\/uploads\\\/2015\\\/08\\\/JAZZZEITUNGDE_Logo_Neu.png?resize=96%2C96&ssl=1\",\"caption\":\"Redaktion JazzZeitung\"},\"description\":\"Artikel der Redaktion der JazzZeitung.\",\"sameAs\":[\"http:\\\/\\\/www.jazzzeitung.de\\\/cms\\\/\"],\"url\":\"https:\\\/\\\/www.jazzzeitung.de\\\/cms\\\/author\\\/redaktion\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u201eEssen-Jazz-Orchestra\u201c am 30. April in der Casa des Schauspiel Essen - JazzZeitung","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.jazzzeitung.de\/cms\/2017\/04\/essen-jazz-orchestra-am-30-april-in-der-casa-des-schauspiel-essen\/","og_locale":"de_DE","og_type":"article","og_title":"\u201eEssen-Jazz-Orchestra\u201c am 30. April in der Casa des Schauspiel Essen - JazzZeitung","og_description":"Lange galten sie als die Elefanten unter den Jazz-Besetzungen, denn unter einem Dutzend Instrumentalisten kommt keine Big Band aus. Und auch das Image dieser Orchester war in den vergangenen Jahrzehnten eher durchwachsen: Da war die Rede von \u201eOpa-Musik\u201c und \u201eSchnee von gestern\u201c. Nachdem allerdings Robbie Williams seine Frank-Sinatra-Hommage \u201eSwing When You&#8217;re Winning\u201c herausgebracht hatte und Roger Cicero mit seinem Hitalbum \u201eM\u00e4nnersachen\u201c gro\u00dfe Erfolge feiern konnte, wendete sich das Blatt: Auch eine neue Generation von Musikern entdeckte die Klangkraft solcher Formationen f\u00fcr sich und experimentierte nach Lust und Laune in gro\u00dfer Besetzung. Im Ruhrgebiet hat sich f\u00fcr Freunde des satten Big-Band-Sounds das \u201eEssen-Jazz-Orchestra\u201c mittlerweile zu einer festen Gr\u00f6\u00dfe entwickelt. Die Truppe, die aus Absolventen der Essener Folkwang Universit\u00e4t der K\u00fcnste und Musikern der freien Jazz-Szene Essens besteht, pr\u00e4sentiert bei ihren Konzerten vorrangig St\u00fccke, die von einigen Ensemblemitgliedern selbst komponiert wurden. Welche aktuellen Neukompositionen das \u201eEssen-Jazz-Orchestra\u201c unter der Leitung von Tobias Sch\u00fctte bei seinem n\u00e4chsten Auftritt am Sonntag, dem 30. April ab 19 Uhr in die Casa des Schauspiel Essen spielen wird, steht derzeit noch nicht fest, aber das ist sicher: Es gibt wieder reichlich Futter f\u00fcr &hellip;","og_url":"https:\/\/www.jazzzeitung.de\/cms\/2017\/04\/essen-jazz-orchestra-am-30-april-in-der-casa-des-schauspiel-essen\/","og_site_name":"JazzZeitung","article_publisher":"https:\/\/www.facebook.com\/JazzZeitung\/","article_published_time":"2017-04-21T08:55:20+00:00","og_image":[{"url":"http:\/\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2017\/04\/Essen-Jazz-Orchestra_2-150x150.jpg","type":"","width":"","height":""}],"author":"Redaktion JazzZeitung","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.jazzzeitung.de\/cms\/2017\/04\/essen-jazz-orchestra-am-30-april-in-der-casa-des-schauspiel-essen\/#article","isPartOf":{"@id":"https:\/\/www.jazzzeitung.de\/cms\/2017\/04\/essen-jazz-orchestra-am-30-april-in-der-casa-des-schauspiel-essen\/"},"author":{"name":"Redaktion JazzZeitung","@id":"https:\/\/www.jazzzeitung.de\/cms\/#\/schema\/person\/2245b36b9cd1d24cea10f01c031fb92b"},"headline":"\u201eEssen-Jazz-Orchestra\u201c am 30. April in der Casa des Schauspiel Essen","datePublished":"2017-04-21T08:55:20+00:00","mainEntityOfPage":{"@id":"https:\/\/www.jazzzeitung.de\/cms\/2017\/04\/essen-jazz-orchestra-am-30-april-in-der-casa-des-schauspiel-essen\/"},"wordCount":304,"commentCount":0,"publisher":{"@id":"https:\/\/www.jazzzeitung.de\/cms\/#organization"},"image":{"@id":"https:\/\/www.jazzzeitung.de\/cms\/2017\/04\/essen-jazz-orchestra-am-30-april-in-der-casa-des-schauspiel-essen\/#primaryimage"},"thumbnailUrl":"http:\/\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2017\/04\/Essen-Jazz-Orchestra_2-150x150.jpg","keywords":["Big Band","Essen","Robbie Williams","Swing","Tickets"],"articleSection":["News"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.jazzzeitung.de\/cms\/2017\/04\/essen-jazz-orchestra-am-30-april-in-der-casa-des-schauspiel-essen\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.jazzzeitung.de\/cms\/2017\/04\/essen-jazz-orchestra-am-30-april-in-der-casa-des-schauspiel-essen\/","url":"https:\/\/www.jazzzeitung.de\/cms\/2017\/04\/essen-jazz-orchestra-am-30-april-in-der-casa-des-schauspiel-essen\/","name":"\u201eEssen-Jazz-Orchestra\u201c am 30. April in der Casa des Schauspiel Essen - JazzZeitung","isPartOf":{"@id":"https:\/\/www.jazzzeitung.de\/cms\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.jazzzeitung.de\/cms\/2017\/04\/essen-jazz-orchestra-am-30-april-in-der-casa-des-schauspiel-essen\/#primaryimage"},"image":{"@id":"https:\/\/www.jazzzeitung.de\/cms\/2017\/04\/essen-jazz-orchestra-am-30-april-in-der-casa-des-schauspiel-essen\/#primaryimage"},"thumbnailUrl":"http:\/\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2017\/04\/Essen-Jazz-Orchestra_2-150x150.jpg","datePublished":"2017-04-21T08:55:20+00:00","breadcrumb":{"@id":"https:\/\/www.jazzzeitung.de\/cms\/2017\/04\/essen-jazz-orchestra-am-30-april-in-der-casa-des-schauspiel-essen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.jazzzeitung.de\/cms\/2017\/04\/essen-jazz-orchestra-am-30-april-in-der-casa-des-schauspiel-essen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.jazzzeitung.de\/cms\/2017\/04\/essen-jazz-orchestra-am-30-april-in-der-casa-des-schauspiel-essen\/#primaryimage","url":"http:\/\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2017\/04\/Essen-Jazz-Orchestra_2-150x150.jpg","contentUrl":"http:\/\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2017\/04\/Essen-Jazz-Orchestra_2-150x150.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.jazzzeitung.de\/cms\/2017\/04\/essen-jazz-orchestra-am-30-april-in-der-casa-des-schauspiel-essen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.jazzzeitung.de\/cms\/"},{"@type":"ListItem","position":2,"name":"\u201eEssen-Jazz-Orchestra\u201c am 30. April in der Casa des Schauspiel Essen"}]},{"@type":"WebSite","@id":"https:\/\/www.jazzzeitung.de\/cms\/#website","url":"https:\/\/www.jazzzeitung.de\/cms\/","name":"JazzZeitung","description":"Jazz-News und Jazz-Kontroverses","publisher":{"@id":"https:\/\/www.jazzzeitung.de\/cms\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.jazzzeitung.de\/cms\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.jazzzeitung.de\/cms\/#organization","name":"JazzZeitung online","url":"https:\/\/www.jazzzeitung.de\/cms\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.jazzzeitung.de\/cms\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2015\/08\/JAZZZEITUNGDE_Logo_Neu.png?fit=499%2C200&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2015\/08\/JAZZZEITUNGDE_Logo_Neu.png?fit=499%2C200&ssl=1","width":499,"height":200,"caption":"JazzZeitung online"},"image":{"@id":"https:\/\/www.jazzzeitung.de\/cms\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/JazzZeitung\/"]},{"@type":"Person","@id":"https:\/\/www.jazzzeitung.de\/cms\/#\/schema\/person\/2245b36b9cd1d24cea10f01c031fb92b","name":"Redaktion JazzZeitung","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2015\/08\/JAZZZEITUNGDE_Logo_Neu.png?resize=96%2C96&ssl=159975dcacb611b5700bd619b5daf0a7a","url":"https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2015\/08\/JAZZZEITUNGDE_Logo_Neu.png?resize=96%2C96&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2015\/08\/JAZZZEITUNGDE_Logo_Neu.png?resize=96%2C96&ssl=1","caption":"Redaktion JazzZeitung"},"description":"Artikel der Redaktion der JazzZeitung.","sameAs":["http:\/\/www.jazzzeitung.de\/cms\/"],"url":"https:\/\/www.jazzzeitung.de\/cms\/author\/redaktion\/"}]}},"wp-worthy-pixel":{"ignored":false,"public":null,"server":null,"url":null},"wp-worthy-type":"normal","jetpack_publicize_connections":[],"cc_featured_image_caption":{"caption_text":false,"source_text":false,"source_url":false},"jetpack_shortlink":"https:\/\/wp.me\/p3KEcT-3a4","jetpack-related-posts":[{"id":18754,"url":"https:\/\/www.jazzzeitung.de\/cms\/2019\/02\/news-tamir-hendelman-trio-und-saengerin-niki-haris-auf-der-piano-buehne-in-oberthulba-urauffuehrung-in-essen-essence-of-air-vom-essen-jazz-orchestra\/","url_meta":{"origin":12156,"position":0},"title":"+++ News: +++ Tamir Hendelman-Trio und S\u00e4ngerin Niki Haris auf der Piano-B\u00fchne in Oberthulba +++Urauff\u00fchrung in Essen: \u201eEssence of Air&#8220; vom Essen Jazz Orchestra +++","author":"Redaktion JazzZeitung","date":"26. Februar 2019","format":false,"excerpt":"Soul, Blues, Funky Swing, und Jazz: Niki Haris begleitet von Tamir Hendelman in Oberthulba Am Freitag, den 29. M\u00e4rz 2019 pr\u00e4sentiert die Piano-B\u00fchne in Oberthulba das Tamir Hendelman-Trio und die US-amerikanische S\u00e4ngerin Niki Haris. Niki Haris war B\u00fchnenpartner von\u00a0 Ray Charles, Stanley Turrentine, Whitney Houston , Tom Jones,\u00a0 Madonna und\u2026","rel":"","context":"In &quot;News&quot;","block_context":{"text":"News","link":"https:\/\/www.jazzzeitung.de\/cms\/thema\/nachrichten\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2019\/02\/Beitragsbild-Niki-Haris-BW-High-Res.jpg?fit=1200%2C1188&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2019\/02\/Beitragsbild-Niki-Haris-BW-High-Res.jpg?fit=1200%2C1188&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2019\/02\/Beitragsbild-Niki-Haris-BW-High-Res.jpg?fit=1200%2C1188&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2019\/02\/Beitragsbild-Niki-Haris-BW-High-Res.jpg?fit=1200%2C1188&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2019\/02\/Beitragsbild-Niki-Haris-BW-High-Res.jpg?fit=1200%2C1188&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":20685,"url":"https:\/\/www.jazzzeitung.de\/cms\/2019\/09\/news-13-bayreuther-jazz-november-2019-das-essen-jazz-orchestra-erhaelt-den-jazz-pott-2019\/","url_meta":{"origin":12156,"position":1},"title":"+++ News +++ 13. Bayreuther Jazz-November 2019 +++ Das Essen Jazz Orchestra erh\u00e4lt den \u201eJazz Pott\u201c 2019 +++","author":"Redaktion JazzZeitung","date":"16. September 2019","format":false,"excerpt":"+++ 13. Bayreuther Jazz-November 2019 +++ Der 13. Bayreuther Jazznovember zeigt vom 7. bis zum 10. November viele Facetten: Die Spannweite reicht vom Pianoabend im gro\u00dfen Konzertsaal \u00fcber die Tanzparty im Frisco bis zum experimentellen Crossover auf der Kellerb\u00fchne. Die auftretenden K\u00fcnstler sehen aus ganz unterschiedlichen Blickwinkeln aufs Leben, und\u2026","rel":"","context":"In &quot;News&quot;","block_context":{"text":"News","link":"https:\/\/www.jazzzeitung.de\/cms\/thema\/nachrichten\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2019\/09\/Wallace-Roney-by-H-J-Maquet.jpg?fit=1200%2C866&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2019\/09\/Wallace-Roney-by-H-J-Maquet.jpg?fit=1200%2C866&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2019\/09\/Wallace-Roney-by-H-J-Maquet.jpg?fit=1200%2C866&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2019\/09\/Wallace-Roney-by-H-J-Maquet.jpg?fit=1200%2C866&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2019\/09\/Wallace-Roney-by-H-J-Maquet.jpg?fit=1200%2C866&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":26719,"url":"https:\/\/www.jazzzeitung.de\/cms\/2022\/02\/news-erfurter-reihe-jazz-stream-midnight-swingstars-in-itzehoe-kurt-rosenwinkel-in-essen\/","url_meta":{"origin":12156,"position":2},"title":"+++ news +++  Erfurter Reihe &#8222;Jazz Stream&#8220; +++ Midnight Swingstars in Itzehoe +++ Kurt Rosenwinkel in Essen +++","author":"Redaktion JazzZeitung","date":"9. Februar 2022","format":false,"excerpt":"+++ Erfurter Reihe \"Jazz Stream\" feiert einj\u00e4hriges Bestehen +++ Im Januar 2021 hatte der Erfurter Musiker Marcus Horn, Schlagzeug-Absolvent der Musikhochschule Weimar, die Reihe \"Jazz-Stream\" ins Leben gerufen. Mit einer Stunde gestreamter Jazzmusik auf YouTube, sollte Live-Musikbetrieb auch w\u00e4hrend der Pandemie aufrecht erhalten werden. Am 07.02. feierte die Reihe ihr\u2026","rel":"","context":"In &quot;News&quot;","block_context":{"text":"News","link":"https:\/\/www.jazzzeitung.de\/cms\/thema\/nachrichten\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2022\/02\/J2.jpg?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2022\/02\/J2.jpg?fit=1200%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2022\/02\/J2.jpg?fit=1200%2C800&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2022\/02\/J2.jpg?fit=1200%2C800&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2022\/02\/J2.jpg?fit=1200%2C800&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":20779,"url":"https:\/\/www.jazzzeitung.de\/cms\/2019\/10\/news-brazooka-im-raven-in-straubing-jazz-pott-preistraeger-mit-heimspiel\/","url_meta":{"origin":12156,"position":3},"title":"+++ News +++ Brazooka im Raven in Straubing +++ \u201eJazz Pott\u201c-Preistr\u00e4ger mit Heimspiel +++","author":"Redaktion JazzZeitung","date":"2. Oktober 2019","format":false,"excerpt":"+++ Brazooka im Raven in Straubing +++ BRAZZOOKA \u2013 das sind kraftvolle Rhythmen und raffinierte Harmonien mit Elementen aus Funk, Jazz und Soul, die zu einem elektrisierenden Klangerlebnis verschmelzen. Die neunk\u00f6pfige Combo aus dem Raum Regensburg bewegt sich stilsicher durch mehr als f\u00fcnf Jahrzehnte einschl\u00e4giger Musikgeschichte: Im Repertoire finden sich\u2026","rel":"","context":"In &quot;News&quot;","block_context":{"text":"News","link":"https:\/\/www.jazzzeitung.de\/cms\/thema\/nachrichten\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2019\/10\/P1180005.jpg?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2019\/10\/P1180005.jpg?fit=1200%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2019\/10\/P1180005.jpg?fit=1200%2C800&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2019\/10\/P1180005.jpg?fit=1200%2C800&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2019\/10\/P1180005.jpg?fit=1200%2C800&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":5995,"url":"https:\/\/www.jazzzeitung.de\/cms\/2015\/05\/nicht-ohne-tanz-und-essen-jazz-kapstadt\/","url_meta":{"origin":12156,"position":4},"title":"Nicht ohne Tanz und Essen \u2013 Jazz in Kapstadt","author":"Redaktion JazzZeitung","date":"2. Mai 2015","format":false,"excerpt":"Von Antje R\u00f6\u00dfler - Das s\u00fcdafrikanische Kapstadt ist ein Eldorado f\u00fcr den Jazz. Nicht umsonst wurden der Stadt zu F\u00fc\u00dfen des Tafelbergs etliche Musikst\u00fccke und sogar ganze Alben gewidmet. Schon ein kurzes Name-dropping offenbart das hiesige Niveau des Musizierens: der Pianist Abdullah Ibrahim, der Saxophonist Winston Mankunku oder der Gitarrist\u2026","rel":"","context":"In &quot;Bericht&quot;","block_context":{"text":"Bericht","link":"https:\/\/www.jazzzeitung.de\/cms\/thema\/bericht\/"},"img":{"alt_text":"uploads_images_Media_gallery_Culture","src":"https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2015\/04\/uploads_images_Media_gallery_Culture-150x150.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":9381,"url":"https:\/\/www.jazzzeitung.de\/cms\/2016\/05\/news-adam-baldych-imaginary-quartet-groebenzell-und-starnberg-kartenvorverkauf-fuer-die-jazz-essen-saison-20162017-beginnt-tom-gaebel-wird-musikpate\/","url_meta":{"origin":12156,"position":5},"title":"+++ News: +++ Adam Ba\u0142dych Imaginary Quartet in Gr\u00f6benzell und Starnberg +++ Kartenvorverkauf f\u00fcr die \u201eJazz in Essen\u201c-Saison 2016\/2017 beginnt +++ Tom Gaebel wird Musikpate +++","author":"Redaktion JazzZeitung","date":"24. Mai 2016","format":false,"excerpt":"Der polnische Star-Jazzgeiger Adam Ba\u0142dych kommt nach Bayern Am 2. Juni tritt er zuerst mit seiner Band, dem \"Adam Ba\u0142dych Imaginary Quartet\" in Gr\u00f6benzell auf. Tags drauf kann man sie in Starnberg im\u00a0 gro\u00dfen Saal der Schlossberghalle sehen und h\u00f6ren. Der 1986-geborene polnische Jazzer tourt immer wieder durch Europa, Amerika\u2026","rel":"","context":"In &quot;News&quot;","block_context":{"text":"News","link":"https:\/\/www.jazzzeitung.de\/cms\/thema\/nachrichten\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2016\/05\/adam-baldych.jpg?resize=350%2C200","width":350,"height":200},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.jazzzeitung.de\/cms\/wp-json\/wp\/v2\/posts\/12156","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jazzzeitung.de\/cms\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jazzzeitung.de\/cms\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jazzzeitung.de\/cms\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jazzzeitung.de\/cms\/wp-json\/wp\/v2\/comments?post=12156"}],"version-history":[{"count":1,"href":"https:\/\/www.jazzzeitung.de\/cms\/wp-json\/wp\/v2\/posts\/12156\/revisions"}],"predecessor-version":[{"id":12158,"href":"https:\/\/www.jazzzeitung.de\/cms\/wp-json\/wp\/v2\/posts\/12156\/revisions\/12158"}],"wp:attachment":[{"href":"https:\/\/www.jazzzeitung.de\/cms\/wp-json\/wp\/v2\/media?parent=12156"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jazzzeitung.de\/cms\/wp-json\/wp\/v2\/categories?post=12156"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jazzzeitung.de\/cms\/wp-json\/wp\/v2\/tags?post=12156"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jazzzeitung.de\/cms\/wp-json\/wp\/v2\/coauthors?post=12156"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}