{"id":10050,"date":"2016-09-19T12:00:06","date_gmt":"2016-09-19T10:00:06","guid":{"rendered":"http:\/\/www.jazzzeitung.de\/cms\/?p=10050"},"modified":"2016-09-19T15:47:06","modified_gmt":"2016-09-19T13:47:06","slug":"sich-gekehrt-praesentiert-sich-broenner-auf-seinem-neuen-album-the-good-times","status":"publish","type":"post","link":"https:\/\/www.jazzzeitung.de\/cms\/2016\/09\/sich-gekehrt-praesentiert-sich-broenner-auf-seinem-neuen-album-the-good-times\/","title":{"rendered":"In sich gekehrt pr\u00e4sentiert sich Till Br\u00f6nner auf seinem neuen Album \u2013 &#8222;The Good Times&#8220;"},"content":{"rendered":"<figure id=\"attachment_10051\" aria-describedby=\"caption-attachment-10051\" style=\"width: 150px\" class=\"wp-caption alignright\"><a href=\"https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2016\/09\/71WuDWSj2GL._SL1200_.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"10051\" data-permalink=\"https:\/\/www.jazzzeitung.de\/cms\/2016\/09\/sich-gekehrt-praesentiert-sich-broenner-auf-seinem-neuen-album-the-good-times\/71wudwsj2gl-_sl1200_\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2016\/09\/71WuDWSj2GL._SL1200_.jpg?fit=1200%2C1200&amp;ssl=1\" data-orig-size=\"1200,1200\" data-comments-opened=\"1\" data-image-title=\"71wudwsj2gl-_sl1200_\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Deutschlands wohl bekanntester Jazz-Musiker&lt;\/p&gt;\n\" data-large-file=\"https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2016\/09\/71WuDWSj2GL._SL1200_.jpg?fit=600%2C600&amp;ssl=1\" class=\"size-thumbnail wp-image-10051\" src=\"https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2016\/09\/71WuDWSj2GL._SL1200_-150x150.jpg?resize=150%2C150\" alt=\"Deutschlands wohl bekanntester Jazz-Musiker\" width=\"150\" height=\"150\" srcset=\"https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2016\/09\/71WuDWSj2GL._SL1200_.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2016\/09\/71WuDWSj2GL._SL1200_.jpg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2016\/09\/71WuDWSj2GL._SL1200_.jpg?resize=768%2C768&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2016\/09\/71WuDWSj2GL._SL1200_.jpg?resize=600%2C600&amp;ssl=1 600w, https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2016\/09\/71WuDWSj2GL._SL1200_.jpg?resize=144%2C144&amp;ssl=1 144w, https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2016\/09\/71WuDWSj2GL._SL1200_.jpg?resize=96%2C96&amp;ssl=1 96w, https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2016\/09\/71WuDWSj2GL._SL1200_.jpg?resize=24%2C24&amp;ssl=1 24w, https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2016\/09\/71WuDWSj2GL._SL1200_.jpg?resize=36%2C36&amp;ssl=1 36w, https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2016\/09\/71WuDWSj2GL._SL1200_.jpg?resize=48%2C48&amp;ssl=1 48w, https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2016\/09\/71WuDWSj2GL._SL1200_.jpg?resize=64%2C64&amp;ssl=1 64w, https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2016\/09\/71WuDWSj2GL._SL1200_.jpg?resize=32%2C32&amp;ssl=1 32w, https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2016\/09\/71WuDWSj2GL._SL1200_.jpg?resize=50%2C50&amp;ssl=1 50w, https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2016\/09\/71WuDWSj2GL._SL1200_.jpg?resize=128%2C128&amp;ssl=1 128w, https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2016\/09\/71WuDWSj2GL._SL1200_.jpg?w=1200&amp;ssl=1 1200w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a><figcaption id=\"caption-attachment-10051\" class=\"wp-caption-text\">Deutschlands wohl bekanntester Jazz-Musiker: Till Br\u00f6nner<\/figcaption><\/figure>\n<p>Den Echo hat er schon im Jazz, in der klassischen Musik und in der Popul\u00e4rmusik gewonnen &#8211;\u00a0 Till Br\u00f6nners Einspielungen sind ein Erfolgsgarant f\u00fcr die Plattenfirmen, neulich wurde er sogar vom amerikanischen Pr\u00e4sidenten h\u00f6chstpers\u00f6nlich ins Wei\u00dfe Haus eingeladen. Nicht nur das Publikum liebt ihn, auch die Fachpresse schreibt regelm\u00e4\u00dfig exzellente Kritiken.<\/p>\n<p>Auf dem neuen Album verwirklichen sich Till Br\u00f6nner und der Produzent Ruud Jacobs mit der St\u00fcckauswahl einen kleinen pers\u00f6nlichen Traum. George Gershwin, Sasha Distel und andere gro\u00dfen Namen wie Irving Berlin sind die Komponisten der 13 St\u00fccke, die sich der deutsche Jazz-Star in neuen Arrangements zu Eigen macht. \u00a0Die Songs, die einst auch von Sinatra gesungen wurden, interpretiert Br\u00f6nner an Trompete, Fl\u00fcgelhorn und als S\u00e4nger. Durchweg eine melancholische Kaminfeuer-Stimmung, die getragen von der Allstar-Band mit Anthony Wilson (guitar), Larry Goldings (piano), John Clayton (bass) und Jeff Hamilton (drums) zum Verweilen und Entspannen einl\u00e4dt. Obwohl der Trompeter die bekanntesten Jazz-Crooner der 20er- und 30er-Jahre zum Vorbild nimmt, macht er sich nicht zu viel Druck und versucht keineswegs die K\u00fcnstler nachzuahmen, was den Aufnahmen eine leichte und unaufgeregt Note verleiht. Musikalische Struktur und transparente Aufnahmequalit\u00e4t ziehen sich durch die 13 Titel, die den popul\u00e4ren Jazz-Croonern in nichts nachstehen. An manchen Stellen muss man doch stark sein, denn einige Songs werden von Br\u00f6nner selbst gesungen. Das einladende musikalische Bett der Band bildet allerdings ein wunderbares Fundament und damit passt seine Stimme mit der zarten und luftigen Art doch gut ins Gesamtbild; auch wenn sie bei weitem nicht an sein charismatisches Trompeten- und Fl\u00fcgelhornspiel heranreicht. Die Band um Br\u00f6nner l\u00e4sst sich vom pl\u00e4tschernden Groove dahintreiben und f\u00e4llt nicht aus der smoothen Jazzatmosph\u00e4re heraus, wodurch eine stimmige Gesamtwirkung erzeugt wird. \u00dcberraschende und spontane Momente finden sich dadurch leider meist vergeblich.<\/p>\n<p>Br\u00f6nners Kernkompetenz, das Spiel auf der Trompete, bleibt wie in all den vorhergegangenen Alben brillant und auch das Fl\u00fcgelhorn als musikalisches Crooner-Instrument, mit dem intimen und warmen Klang geht hervorragend mit den Arrangements einher. Passend ist auch das reduzierte, manchmal fast minimalistische Trompetenspiel, welches das Album zu einer Empfehlung f\u00fcr Jazz-Kenner und Laien macht. Eine melancholische und romantisch anmutende Platte f\u00fcr den Beginn der Herbsttage.<\/p>\n<p>&nbsp;<\/p>\n<p>Charlotte Oelschlegel<\/p>\n<p>&nbsp;<\/p>\n<p>Die 13 Titel sind:<\/p>\n<ul>\n<li>The Good Life<\/li>\n<li>Sweet Lorraine<\/li>\n<li>For All We Know<\/li>\n<li>Come Dance with Me<\/li>\n<li>Change Partners<\/li>\n<li>Love is Here to Stay<\/li>\n<li>I Loves You, Porgy<\/li>\n<li>I May Be Wrong<\/li>\n<li>O Que Resta<\/li>\n<li>I\u00b4m Confessin that I Love You<\/li>\n<li>I\u00b4ll Be Seeing You<\/li>\n<li>Her Smile<\/li>\n<li>In the Wee Small Hours of the Morning<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Den Echo hat er schon im Jazz, in der klassischen Musik und in der Popul\u00e4rmusik gewonnen &#8211;\u00a0 Till Br\u00f6nners Einspielungen sind ein Erfolgsgarant f\u00fcr die Plattenfirmen, neulich wurde er sogar vom amerikanischen Pr\u00e4sidenten h\u00f6chstpers\u00f6nlich ins Wei\u00dfe Haus eingeladen. Nicht nur das Publikum liebt ihn, auch die Fachpresse schreibt regelm\u00e4\u00dfig exzellente Kritiken. Auf dem neuen Album verwirklichen sich Till Br\u00f6nner und der Produzent Ruud Jacobs mit der St\u00fcckauswahl einen kleinen pers\u00f6nlichen Traum. George Gershwin, Sasha Distel und andere gro\u00dfen Namen wie Irving Berlin sind die Komponisten der 13 St\u00fccke, die sich der deutsche Jazz-Star in neuen Arrangements zu Eigen macht. \u00a0Die Songs, die einst auch von Sinatra gesungen wurden, interpretiert Br\u00f6nner an Trompete, Fl\u00fcgelhorn und als S\u00e4nger. Durchweg eine melancholische Kaminfeuer-Stimmung, die getragen von der Allstar-Band mit Anthony Wilson (guitar), Larry Goldings (piano), John Clayton (bass) und Jeff Hamilton (drums) zum Verweilen und Entspannen einl\u00e4dt. Obwohl der Trompeter die bekanntesten Jazz-Crooner der 20er- und 30er-Jahre zum Vorbild nimmt, macht er sich nicht zu viel Druck und versucht keineswegs die K\u00fcnstler nachzuahmen, was den Aufnahmen eine leichte und unaufgeregt Note verleiht. Musikalische Struktur und transparente Aufnahmequalit\u00e4t ziehen &hellip;<\/p>\n","protected":false},"author":18,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1152],"tags":[34,66,980,442,549],"coauthors":[695],"class_list":["post-10050","post","type-post","status-publish","format-standard","hentry","category-rezension","tag-album","tag-berlin","tag-echo","tag-piano","tag-till-broenner"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>In sich gekehrt pr\u00e4sentiert sich Till Br\u00f6nner auf seinem neuen Album \u2013 &quot;The Good Times&quot; - JazzZeitung<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.jazzzeitung.de\/cms\/2016\/09\/sich-gekehrt-praesentiert-sich-broenner-auf-seinem-neuen-album-the-good-times\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"In sich gekehrt pr\u00e4sentiert sich Till Br\u00f6nner auf seinem neuen Album \u2013 &quot;The Good Times&quot; - JazzZeitung\" \/>\n<meta property=\"og:description\" content=\"Den Echo hat er schon im Jazz, in der klassischen Musik und in der Popul\u00e4rmusik gewonnen &#8211;\u00a0 Till Br\u00f6nners Einspielungen sind ein Erfolgsgarant f\u00fcr die Plattenfirmen, neulich wurde er sogar vom amerikanischen Pr\u00e4sidenten h\u00f6chstpers\u00f6nlich ins Wei\u00dfe Haus eingeladen. Nicht nur das Publikum liebt ihn, auch die Fachpresse schreibt regelm\u00e4\u00dfig exzellente Kritiken. Auf dem neuen Album verwirklichen sich Till Br\u00f6nner und der Produzent Ruud Jacobs mit der St\u00fcckauswahl einen kleinen pers\u00f6nlichen Traum. George Gershwin, Sasha Distel und andere gro\u00dfen Namen wie Irving Berlin sind die Komponisten der 13 St\u00fccke, die sich der deutsche Jazz-Star in neuen Arrangements zu Eigen macht. \u00a0Die Songs, die einst auch von Sinatra gesungen wurden, interpretiert Br\u00f6nner an Trompete, Fl\u00fcgelhorn und als S\u00e4nger. Durchweg eine melancholische Kaminfeuer-Stimmung, die getragen von der Allstar-Band mit Anthony Wilson (guitar), Larry Goldings (piano), John Clayton (bass) und Jeff Hamilton (drums) zum Verweilen und Entspannen einl\u00e4dt. Obwohl der Trompeter die bekanntesten Jazz-Crooner der 20er- und 30er-Jahre zum Vorbild nimmt, macht er sich nicht zu viel Druck und versucht keineswegs die K\u00fcnstler nachzuahmen, was den Aufnahmen eine leichte und unaufgeregt Note verleiht. Musikalische Struktur und transparente Aufnahmequalit\u00e4t ziehen &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.jazzzeitung.de\/cms\/2016\/09\/sich-gekehrt-praesentiert-sich-broenner-auf-seinem-neuen-album-the-good-times\/\" \/>\n<meta property=\"og:site_name\" content=\"JazzZeitung\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/JazzZeitung\/\" \/>\n<meta property=\"article:published_time\" content=\"2016-09-19T10:00:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-09-19T13:47:06+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2016\/09\/71WuDWSj2GL._SL1200_-150x150.jpg\" \/>\n<meta name=\"author\" content=\"Redaktion JazzZeitung\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.jazzzeitung.de\\\/cms\\\/2016\\\/09\\\/sich-gekehrt-praesentiert-sich-broenner-auf-seinem-neuen-album-the-good-times\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jazzzeitung.de\\\/cms\\\/2016\\\/09\\\/sich-gekehrt-praesentiert-sich-broenner-auf-seinem-neuen-album-the-good-times\\\/\"},\"author\":{\"name\":\"Redaktion JazzZeitung\",\"@id\":\"https:\\\/\\\/www.jazzzeitung.de\\\/cms\\\/#\\\/schema\\\/person\\\/2245b36b9cd1d24cea10f01c031fb92b\"},\"headline\":\"In sich gekehrt pr\u00e4sentiert sich Till Br\u00f6nner auf seinem neuen Album \u2013 &#8222;The Good Times&#8220;\",\"datePublished\":\"2016-09-19T10:00:06+00:00\",\"dateModified\":\"2016-09-19T13:47:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.jazzzeitung.de\\\/cms\\\/2016\\\/09\\\/sich-gekehrt-praesentiert-sich-broenner-auf-seinem-neuen-album-the-good-times\\\/\"},\"wordCount\":470,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.jazzzeitung.de\\\/cms\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.jazzzeitung.de\\\/cms\\\/2016\\\/09\\\/sich-gekehrt-praesentiert-sich-broenner-auf-seinem-neuen-album-the-good-times\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.jazzzeitung.de\\\/cms\\\/wp-content\\\/uploads\\\/2016\\\/09\\\/71WuDWSj2GL._SL1200_-150x150.jpg\",\"keywords\":[\"Album\",\"Berlin\",\"ECHO\",\"Piano\",\"Till Br\u00f6nner\"],\"articleSection\":[\"Rezension\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.jazzzeitung.de\\\/cms\\\/2016\\\/09\\\/sich-gekehrt-praesentiert-sich-broenner-auf-seinem-neuen-album-the-good-times\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.jazzzeitung.de\\\/cms\\\/2016\\\/09\\\/sich-gekehrt-praesentiert-sich-broenner-auf-seinem-neuen-album-the-good-times\\\/\",\"url\":\"https:\\\/\\\/www.jazzzeitung.de\\\/cms\\\/2016\\\/09\\\/sich-gekehrt-praesentiert-sich-broenner-auf-seinem-neuen-album-the-good-times\\\/\",\"name\":\"In sich gekehrt pr\u00e4sentiert sich Till Br\u00f6nner auf seinem neuen Album \u2013 \\\"The Good Times\\\" - JazzZeitung\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jazzzeitung.de\\\/cms\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.jazzzeitung.de\\\/cms\\\/2016\\\/09\\\/sich-gekehrt-praesentiert-sich-broenner-auf-seinem-neuen-album-the-good-times\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.jazzzeitung.de\\\/cms\\\/2016\\\/09\\\/sich-gekehrt-praesentiert-sich-broenner-auf-seinem-neuen-album-the-good-times\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.jazzzeitung.de\\\/cms\\\/wp-content\\\/uploads\\\/2016\\\/09\\\/71WuDWSj2GL._SL1200_-150x150.jpg\",\"datePublished\":\"2016-09-19T10:00:06+00:00\",\"dateModified\":\"2016-09-19T13:47:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.jazzzeitung.de\\\/cms\\\/2016\\\/09\\\/sich-gekehrt-praesentiert-sich-broenner-auf-seinem-neuen-album-the-good-times\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.jazzzeitung.de\\\/cms\\\/2016\\\/09\\\/sich-gekehrt-praesentiert-sich-broenner-auf-seinem-neuen-album-the-good-times\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.jazzzeitung.de\\\/cms\\\/2016\\\/09\\\/sich-gekehrt-praesentiert-sich-broenner-auf-seinem-neuen-album-the-good-times\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.jazzzeitung.de\\\/cms\\\/wp-content\\\/uploads\\\/2016\\\/09\\\/71WuDWSj2GL._SL1200_-150x150.jpg\",\"contentUrl\":\"http:\\\/\\\/www.jazzzeitung.de\\\/cms\\\/wp-content\\\/uploads\\\/2016\\\/09\\\/71WuDWSj2GL._SL1200_-150x150.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.jazzzeitung.de\\\/cms\\\/2016\\\/09\\\/sich-gekehrt-praesentiert-sich-broenner-auf-seinem-neuen-album-the-good-times\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.jazzzeitung.de\\\/cms\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"In sich gekehrt pr\u00e4sentiert sich Till Br\u00f6nner auf seinem neuen Album \u2013 &#8222;The Good Times&#8220;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.jazzzeitung.de\\\/cms\\\/#website\",\"url\":\"https:\\\/\\\/www.jazzzeitung.de\\\/cms\\\/\",\"name\":\"JazzZeitung\",\"description\":\"Jazz-News und Jazz-Kontroverses\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.jazzzeitung.de\\\/cms\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.jazzzeitung.de\\\/cms\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.jazzzeitung.de\\\/cms\\\/#organization\",\"name\":\"JazzZeitung online\",\"url\":\"https:\\\/\\\/www.jazzzeitung.de\\\/cms\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.jazzzeitung.de\\\/cms\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.jazzzeitung.de\\\/cms\\\/wp-content\\\/uploads\\\/2015\\\/08\\\/JAZZZEITUNGDE_Logo_Neu.png?fit=499%2C200&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.jazzzeitung.de\\\/cms\\\/wp-content\\\/uploads\\\/2015\\\/08\\\/JAZZZEITUNGDE_Logo_Neu.png?fit=499%2C200&ssl=1\",\"width\":499,\"height\":200,\"caption\":\"JazzZeitung online\"},\"image\":{\"@id\":\"https:\\\/\\\/www.jazzzeitung.de\\\/cms\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/JazzZeitung\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.jazzzeitung.de\\\/cms\\\/#\\\/schema\\\/person\\\/2245b36b9cd1d24cea10f01c031fb92b\",\"name\":\"Redaktion JazzZeitung\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/i0.wp.com\\\/www.jazzzeitung.de\\\/cms\\\/wp-content\\\/uploads\\\/2015\\\/08\\\/JAZZZEITUNGDE_Logo_Neu.png?resize=96%2C96&ssl=159975dcacb611b5700bd619b5daf0a7a\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.jazzzeitung.de\\\/cms\\\/wp-content\\\/uploads\\\/2015\\\/08\\\/JAZZZEITUNGDE_Logo_Neu.png?resize=96%2C96&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.jazzzeitung.de\\\/cms\\\/wp-content\\\/uploads\\\/2015\\\/08\\\/JAZZZEITUNGDE_Logo_Neu.png?resize=96%2C96&ssl=1\",\"caption\":\"Redaktion JazzZeitung\"},\"description\":\"Artikel der Redaktion der JazzZeitung.\",\"sameAs\":[\"http:\\\/\\\/www.jazzzeitung.de\\\/cms\\\/\"],\"url\":\"https:\\\/\\\/www.jazzzeitung.de\\\/cms\\\/author\\\/redaktion\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"In sich gekehrt pr\u00e4sentiert sich Till Br\u00f6nner auf seinem neuen Album \u2013 \"The Good Times\" - JazzZeitung","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.jazzzeitung.de\/cms\/2016\/09\/sich-gekehrt-praesentiert-sich-broenner-auf-seinem-neuen-album-the-good-times\/","og_locale":"de_DE","og_type":"article","og_title":"In sich gekehrt pr\u00e4sentiert sich Till Br\u00f6nner auf seinem neuen Album \u2013 \"The Good Times\" - JazzZeitung","og_description":"Den Echo hat er schon im Jazz, in der klassischen Musik und in der Popul\u00e4rmusik gewonnen &#8211;\u00a0 Till Br\u00f6nners Einspielungen sind ein Erfolgsgarant f\u00fcr die Plattenfirmen, neulich wurde er sogar vom amerikanischen Pr\u00e4sidenten h\u00f6chstpers\u00f6nlich ins Wei\u00dfe Haus eingeladen. Nicht nur das Publikum liebt ihn, auch die Fachpresse schreibt regelm\u00e4\u00dfig exzellente Kritiken. Auf dem neuen Album verwirklichen sich Till Br\u00f6nner und der Produzent Ruud Jacobs mit der St\u00fcckauswahl einen kleinen pers\u00f6nlichen Traum. George Gershwin, Sasha Distel und andere gro\u00dfen Namen wie Irving Berlin sind die Komponisten der 13 St\u00fccke, die sich der deutsche Jazz-Star in neuen Arrangements zu Eigen macht. \u00a0Die Songs, die einst auch von Sinatra gesungen wurden, interpretiert Br\u00f6nner an Trompete, Fl\u00fcgelhorn und als S\u00e4nger. Durchweg eine melancholische Kaminfeuer-Stimmung, die getragen von der Allstar-Band mit Anthony Wilson (guitar), Larry Goldings (piano), John Clayton (bass) und Jeff Hamilton (drums) zum Verweilen und Entspannen einl\u00e4dt. Obwohl der Trompeter die bekanntesten Jazz-Crooner der 20er- und 30er-Jahre zum Vorbild nimmt, macht er sich nicht zu viel Druck und versucht keineswegs die K\u00fcnstler nachzuahmen, was den Aufnahmen eine leichte und unaufgeregt Note verleiht. Musikalische Struktur und transparente Aufnahmequalit\u00e4t ziehen &hellip;","og_url":"https:\/\/www.jazzzeitung.de\/cms\/2016\/09\/sich-gekehrt-praesentiert-sich-broenner-auf-seinem-neuen-album-the-good-times\/","og_site_name":"JazzZeitung","article_publisher":"https:\/\/www.facebook.com\/JazzZeitung\/","article_published_time":"2016-09-19T10:00:06+00:00","article_modified_time":"2016-09-19T13:47:06+00:00","og_image":[{"url":"http:\/\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2016\/09\/71WuDWSj2GL._SL1200_-150x150.jpg","type":"","width":"","height":""}],"author":"Redaktion JazzZeitung","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.jazzzeitung.de\/cms\/2016\/09\/sich-gekehrt-praesentiert-sich-broenner-auf-seinem-neuen-album-the-good-times\/#article","isPartOf":{"@id":"https:\/\/www.jazzzeitung.de\/cms\/2016\/09\/sich-gekehrt-praesentiert-sich-broenner-auf-seinem-neuen-album-the-good-times\/"},"author":{"name":"Redaktion JazzZeitung","@id":"https:\/\/www.jazzzeitung.de\/cms\/#\/schema\/person\/2245b36b9cd1d24cea10f01c031fb92b"},"headline":"In sich gekehrt pr\u00e4sentiert sich Till Br\u00f6nner auf seinem neuen Album \u2013 &#8222;The Good Times&#8220;","datePublished":"2016-09-19T10:00:06+00:00","dateModified":"2016-09-19T13:47:06+00:00","mainEntityOfPage":{"@id":"https:\/\/www.jazzzeitung.de\/cms\/2016\/09\/sich-gekehrt-praesentiert-sich-broenner-auf-seinem-neuen-album-the-good-times\/"},"wordCount":470,"commentCount":0,"publisher":{"@id":"https:\/\/www.jazzzeitung.de\/cms\/#organization"},"image":{"@id":"https:\/\/www.jazzzeitung.de\/cms\/2016\/09\/sich-gekehrt-praesentiert-sich-broenner-auf-seinem-neuen-album-the-good-times\/#primaryimage"},"thumbnailUrl":"http:\/\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2016\/09\/71WuDWSj2GL._SL1200_-150x150.jpg","keywords":["Album","Berlin","ECHO","Piano","Till Br\u00f6nner"],"articleSection":["Rezension"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.jazzzeitung.de\/cms\/2016\/09\/sich-gekehrt-praesentiert-sich-broenner-auf-seinem-neuen-album-the-good-times\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.jazzzeitung.de\/cms\/2016\/09\/sich-gekehrt-praesentiert-sich-broenner-auf-seinem-neuen-album-the-good-times\/","url":"https:\/\/www.jazzzeitung.de\/cms\/2016\/09\/sich-gekehrt-praesentiert-sich-broenner-auf-seinem-neuen-album-the-good-times\/","name":"In sich gekehrt pr\u00e4sentiert sich Till Br\u00f6nner auf seinem neuen Album \u2013 \"The Good Times\" - JazzZeitung","isPartOf":{"@id":"https:\/\/www.jazzzeitung.de\/cms\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.jazzzeitung.de\/cms\/2016\/09\/sich-gekehrt-praesentiert-sich-broenner-auf-seinem-neuen-album-the-good-times\/#primaryimage"},"image":{"@id":"https:\/\/www.jazzzeitung.de\/cms\/2016\/09\/sich-gekehrt-praesentiert-sich-broenner-auf-seinem-neuen-album-the-good-times\/#primaryimage"},"thumbnailUrl":"http:\/\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2016\/09\/71WuDWSj2GL._SL1200_-150x150.jpg","datePublished":"2016-09-19T10:00:06+00:00","dateModified":"2016-09-19T13:47:06+00:00","breadcrumb":{"@id":"https:\/\/www.jazzzeitung.de\/cms\/2016\/09\/sich-gekehrt-praesentiert-sich-broenner-auf-seinem-neuen-album-the-good-times\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.jazzzeitung.de\/cms\/2016\/09\/sich-gekehrt-praesentiert-sich-broenner-auf-seinem-neuen-album-the-good-times\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.jazzzeitung.de\/cms\/2016\/09\/sich-gekehrt-praesentiert-sich-broenner-auf-seinem-neuen-album-the-good-times\/#primaryimage","url":"http:\/\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2016\/09\/71WuDWSj2GL._SL1200_-150x150.jpg","contentUrl":"http:\/\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2016\/09\/71WuDWSj2GL._SL1200_-150x150.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.jazzzeitung.de\/cms\/2016\/09\/sich-gekehrt-praesentiert-sich-broenner-auf-seinem-neuen-album-the-good-times\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.jazzzeitung.de\/cms\/"},{"@type":"ListItem","position":2,"name":"In sich gekehrt pr\u00e4sentiert sich Till Br\u00f6nner auf seinem neuen Album \u2013 &#8222;The Good Times&#8220;"}]},{"@type":"WebSite","@id":"https:\/\/www.jazzzeitung.de\/cms\/#website","url":"https:\/\/www.jazzzeitung.de\/cms\/","name":"JazzZeitung","description":"Jazz-News und Jazz-Kontroverses","publisher":{"@id":"https:\/\/www.jazzzeitung.de\/cms\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.jazzzeitung.de\/cms\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.jazzzeitung.de\/cms\/#organization","name":"JazzZeitung online","url":"https:\/\/www.jazzzeitung.de\/cms\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.jazzzeitung.de\/cms\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2015\/08\/JAZZZEITUNGDE_Logo_Neu.png?fit=499%2C200&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2015\/08\/JAZZZEITUNGDE_Logo_Neu.png?fit=499%2C200&ssl=1","width":499,"height":200,"caption":"JazzZeitung online"},"image":{"@id":"https:\/\/www.jazzzeitung.de\/cms\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/JazzZeitung\/"]},{"@type":"Person","@id":"https:\/\/www.jazzzeitung.de\/cms\/#\/schema\/person\/2245b36b9cd1d24cea10f01c031fb92b","name":"Redaktion JazzZeitung","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2015\/08\/JAZZZEITUNGDE_Logo_Neu.png?resize=96%2C96&ssl=159975dcacb611b5700bd619b5daf0a7a","url":"https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2015\/08\/JAZZZEITUNGDE_Logo_Neu.png?resize=96%2C96&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2015\/08\/JAZZZEITUNGDE_Logo_Neu.png?resize=96%2C96&ssl=1","caption":"Redaktion JazzZeitung"},"description":"Artikel der Redaktion der JazzZeitung.","sameAs":["http:\/\/www.jazzzeitung.de\/cms\/"],"url":"https:\/\/www.jazzzeitung.de\/cms\/author\/redaktion\/"}]}},"wp-worthy-pixel":{"ignored":false,"public":"74dfc71db9d54bb8b76c4296924cefc2","server":"vg06.met.vgwort.de\/na","url":"https:\/\/vg06.met.vgwort.de\/na\/74dfc71db9d54bb8b76c4296924cefc2"},"wp-worthy-type":"normal","jetpack_publicize_connections":[],"cc_featured_image_caption":{"caption_text":false,"source_text":false,"source_url":false},"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p3KEcT-2C6","jetpack-related-posts":[{"id":514,"url":"https:\/\/www.jazzzeitung.de\/cms\/2010\/10\/till-broenner-zwischen-jazz-pop-x-factor\/","url_meta":{"origin":10050,"position":0},"title":"Till Br\u00f6nner: zwischen Jazz, Pop &#038; X-Factor","author":"Ursula Gaisa","date":"14. Oktober 2010","format":false,"excerpt":"Also, eigentlich hatte ich mir ja vorgenommen, das Thema Till Br\u00f6nner nicht mehr so schnell an-, bzw. aufzugreifen, aber es scheint doch die Gem\u00fcter zu bewegen. Nach Erscheinen des Artikels von Michael Scheiner zum Leipziger-Jazztage-Konzert Br\u00f6nner-Sommer auf nmz-online kam gleich ein b\u00f6ser Kommentar... Heute erreichte mich unten stehende Pressemeldung zu\u2026","rel":"","context":"In &quot;Blog&quot;","block_context":{"text":"Blog","link":"https:\/\/www.jazzzeitung.de\/cms\/thema\/blog\/"},"img":{"alt_text":"Toll Br\u00f6nner. Foto: Andreas Bitesnich","src":"https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2015\/10\/Till-Broenner_Foto-Andreas-Bitesnich-3.jpg?fit=1200%2C801&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2015\/10\/Till-Broenner_Foto-Andreas-Bitesnich-3.jpg?fit=1200%2C801&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2015\/10\/Till-Broenner_Foto-Andreas-Bitesnich-3.jpg?fit=1200%2C801&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2015\/10\/Till-Broenner_Foto-Andreas-Bitesnich-3.jpg?fit=1200%2C801&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2015\/10\/Till-Broenner_Foto-Andreas-Bitesnich-3.jpg?fit=1200%2C801&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":550,"url":"https:\/\/www.jazzzeitung.de\/cms\/2010\/11\/till-broenner-will-zentrum-fuer-jazz-gruenden\/","url_meta":{"origin":10050,"position":1},"title":"Till Br\u00f6nner will Zentrum f\u00fcr Jazz gr\u00fcnden","author":"Ursula Gaisa","date":"3. November 2010","format":false,"excerpt":"H\u00f6rt, h\u00f6rt: Berlin (dapd). Der Trompeter Till Br\u00f6nner will eine Jazz-Akademie gr\u00fcnden. \"Mein Traum w\u00e4re es, in Berlin an einem wirklich prominenten Ort ein Zentrum f\u00fcr Jazz zu etablieren. In diesem Zentrum w\u00fcrde ein Orchester von ungef\u00e4hr 15 bis 20 Personen sitzen, die t\u00e4glich proben und alle zwei Wochen am\u2026","rel":"","context":"In &quot;Blog&quot;","block_context":{"text":"Blog","link":"https:\/\/www.jazzzeitung.de\/cms\/thema\/blog\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":12420,"url":"https:\/\/www.jazzzeitung.de\/cms\/2017\/05\/news-maxwell-oliveira-trio-im-jazzkeller-huerth-gleuel-am-19-05-17\/","url_meta":{"origin":10050,"position":2},"title":"+++ News +++ &#8222;Maxwell Oliveira Trio&#8220; im Jazzkeller H\u00fcrth-Gleuel am 19.05.17 +++ Star-Trompeter Till Br\u00f6nner sorgt in Kampen erneut f\u00fcr den guten Ton +++","author":"Redaktion JazzZeitung","date":"17. Mai 2017","format":false,"excerpt":"+++ \"Maxwell Oliveira Trio\" im Jazzkeller H\u00fcrth-Gleuel am 19.05.17 +++ Der brasilianische Gitarrist und S\u00e4nger aus Minas Gerais zeigt wof\u00fcr sein Herz schl\u00e4gt: f\u00fcr gute brasilianische Musik wie Samba, Bossa Nova, Bai\u00e3o, Choro, MPB und Folklore. Seine zwei Bachelor in Klassischer Gitarre hat Maxwell Oliveira in seiner Heimat Brasilien und\u2026","rel":"","context":"In &quot;News&quot;","block_context":{"text":"News","link":"https:\/\/www.jazzzeitung.de\/cms\/thema\/nachrichten\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2017\/05\/Max-Olveira-150x150.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":11061,"url":"https:\/\/www.jazzzeitung.de\/cms\/2016\/11\/timm-renner-verwirklicht-till-broenners-traum-vom-house-of-jazz\/","url_meta":{"origin":10050,"position":3},"title":"At the End of the Day: Tim Renner verwirklicht Till Br\u00f6nners Traum vom &#8222;House of Jazz&#8220;","author":"Redaktion JazzZeitung","date":"17. November 2016","format":false,"excerpt":"Schon 2010 tr\u00e4umte der Trompeter Till Br\u00f6nner von einem Zentrum f\u00fcr Jazz an einem \u201eprominenten Ort\u201c, mit eigenem Orchester. Sein Traum scheint nun wahr zu werden. Vergangene Woche stellte der Haushaltsausschuss des Bundestages 12,5 Millionen Euro zur Sanierung der \u201eAlten M\u00fcnze\u201c in der N\u00e4he des Berliner Roten Rathauses bereit. Ausschlaggebend\u2026","rel":"","context":"In &quot;Blog&quot;","block_context":{"text":"Blog","link":"https:\/\/www.jazzzeitung.de\/cms\/thema\/blog\/"},"img":{"alt_text":"Till Br\u00f6nner: At The End Of The Day Island 0602527513683\/Universal","src":"https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2016\/11\/broenner_0-150x150.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":284,"url":"https:\/\/www.jazzzeitung.de\/cms\/2010\/07\/echo-effekt\/","url_meta":{"origin":10050,"position":4},"title":"Echo-Effekt","author":"Rainer Wein","date":"12. Juli 2010","format":false,"excerpt":"\u00dcber den ECHO Jazz ist schon alles gesagt. Obwohl... mir f\u00e4llt da schon noch was ein. Haben wir denn ausreichend gew\u00fcrdigt, dass die Macher des ECHO die allerschlauesten Musikpreismacher der ganzen Galaxis sind? Das f\u00e4ngt ja schon an beim Namen. In Amerika m\u00fcssen Preisnamen immer erst mal hochtrabend klingen, z.B.\u2026","rel":"","context":"In &quot;Blog&quot;","block_context":{"text":"Blog","link":"https:\/\/www.jazzzeitung.de\/cms\/thema\/blog\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":21761,"url":"https:\/\/www.jazzzeitung.de\/cms\/2020\/01\/mit-alter-muenz-bin-ich-dein-prinz-oder-da-house-of-stress-in-berlin\/","url_meta":{"origin":10050,"position":5},"title":"Mit alter M\u00fcnz\u2018 bin ich Dein Prinz, oder: Da House of Stress in Berlin","author":"Huflaikhan","date":"24. Januar 2020","format":false,"excerpt":"Ein Zentrum f\u00fcr die freie Musikszene, ein Haus f\u00fcr die Musik des 21. Jahrhunderts sollte diese Immobilie in Berlin werden. Im Moment produziert sie, die \u201eAlte M\u00fcnze\u201c, allerdings Unbehagen, Ungl\u00fcck bei Vielen und d\u00fcrfte sich nur scheinbar f\u00fcr Wenige jetzt als Gl\u00fccksfall f\u00fcr den Jazz in Berlin, Deutschland und der\u2026","rel":"","context":"In &quot;Blog&quot;","block_context":{"text":"Blog","link":"https:\/\/www.jazzzeitung.de\/cms\/thema\/blog\/"},"img":{"alt_text":"Tag der Musik. Till Br\u00f6nner spielt f\u00fcr Wolfgang Sch\u00e4uble. Foto: Hufner","src":"https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2020\/01\/huf-np-broenner_schaeuble_2012_c_hufnerjpg.jpg?fit=1200%2C795&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2020\/01\/huf-np-broenner_schaeuble_2012_c_hufnerjpg.jpg?fit=1200%2C795&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2020\/01\/huf-np-broenner_schaeuble_2012_c_hufnerjpg.jpg?fit=1200%2C795&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2020\/01\/huf-np-broenner_schaeuble_2012_c_hufnerjpg.jpg?fit=1200%2C795&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.jazzzeitung.de\/cms\/wp-content\/uploads\/2020\/01\/huf-np-broenner_schaeuble_2012_c_hufnerjpg.jpg?fit=1200%2C795&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.jazzzeitung.de\/cms\/wp-json\/wp\/v2\/posts\/10050","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jazzzeitung.de\/cms\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jazzzeitung.de\/cms\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jazzzeitung.de\/cms\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jazzzeitung.de\/cms\/wp-json\/wp\/v2\/comments?post=10050"}],"version-history":[{"count":6,"href":"https:\/\/www.jazzzeitung.de\/cms\/wp-json\/wp\/v2\/posts\/10050\/revisions"}],"predecessor-version":[{"id":10123,"href":"https:\/\/www.jazzzeitung.de\/cms\/wp-json\/wp\/v2\/posts\/10050\/revisions\/10123"}],"wp:attachment":[{"href":"https:\/\/www.jazzzeitung.de\/cms\/wp-json\/wp\/v2\/media?parent=10050"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jazzzeitung.de\/cms\/wp-json\/wp\/v2\/categories?post=10050"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jazzzeitung.de\/cms\/wp-json\/wp\/v2\/tags?post=10050"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jazzzeitung.de\/cms\/wp-json\/wp\/v2\/coauthors?post=10050"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}